{"id":60269,"date":"2026-05-06T10:05:13","date_gmt":"2026-05-06T09:05:13","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=60269"},"modified":"2026-05-06T10:05:13","modified_gmt":"2026-05-06T09:05:13","slug":"capacita-amplia-su-oferta-formativa-con-nuevos-cursos-gratuitos-para-mejorar-la-empleabilidad-en-tenerife","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2026\/05\/06\/capacita-amplia-su-oferta-formativa-con-nuevos-cursos-gratuitos-para-mejorar-la-empleabilidad-en-tenerife\/","title":{"rendered":"Capacita ampl\u00eda su oferta formativa con nuevos cursos gratuitos para mejorar la empleabilidad en Tenerife"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<span style=\"font-weight: 400\">El programa <a href=\"https:\/\/fg.ull.es\/empleo\/capacita\/\" target=\"_blank\" rel=\"noopener\">Capacita<\/a>, impulsado por el Cabildo de Tenerife y la Universidad de La Laguna, a trav\u00e9s de su Fundaci\u00f3n General, refuerza su sexta edici\u00f3n con una ampliaci\u00f3n significativa de su cat\u00e1logo formativo para los pr\u00f3ximos meses.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Capacita combina en un \u00fanico itinerario orientaci\u00f3n laboral, an\u00e1lisis personalizado de competencias y formaci\u00f3n especializada con el objetivo de facilitar el acceso al mercado laboral y mejorar las oportunidades profesionales.\u00a0<\/span><\/p>\n<p><b>Formaci\u00f3n para impulsar la carrera profesional<\/b><\/p>\n<p><span style=\"font-weight: 400\">Los cursos exploran diferentes \u00e1mbitos profesionales para impulsar habilidades, con propuestas como <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030298\/cambio-climatico-y-salud-riesgos-y-soluciones-para-la-sociedad\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">cambio clim\u00e1tico y salud<\/span><\/a><span style=\"font-weight: 400\"> o <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030255\/excel-avanzado\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Excel avanzado<\/span><\/a><span style=\"font-weight: 400\">. As\u00ed como complementos curriculares orientados a la profesionalizaci\u00f3n, con contenidos sobre <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030258\/facturacion-electronica-y-verifactu\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">facturaci\u00f3n electr\u00f3nica<\/span><\/a><span style=\"font-weight: 400\">,\u00a0 <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030257\/obligaciones-fiscales-de-pymes-autonomos-y-profesionales\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">obligaciones fiscales para pymes y personas aut\u00f3nomas<\/span><\/a><span style=\"font-weight: 400\"> o <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030297\/community-manager-gestion-desarrollo-y-mantenimiento-de-comunidades-virtuales\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">gesti\u00f3n de comunidades<\/span><\/a><span style=\"font-weight: 400\"> (<\/span><i><span style=\"font-weight: 400\">Community Manager<\/span><\/i><span style=\"font-weight: 400\">).<\/span><\/p>\n<p><span style=\"font-weight: 400\">A ello se suman formaciones en \u00e1reas emergentes como la <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030178\/ingenieria-de-prompts-e-introduccion-a-sistemas-avanzados-de-ia-generativa\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">inteligencia artificial generativa y la ingenier\u00eda de prompts<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030328\/creacion-de-aplicaciones-moviles-para-android-e-ios-con-flutter\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">desarrollo de aplicaciones m\u00f3viles con Flutter<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030330\/programacion-de-videojuegos-en-unity-videojuegos-2d-basico\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">programaci\u00f3n de videojuegos con Unity<\/span><\/a><span style=\"font-weight: 400\"> o <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030285\/dise-o-para-personajes-en-animacion-2d\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">dise\u00f1o de personajes en animaci\u00f3n 2D<\/span><\/a><span style=\"font-weight: 400\">. Tambi\u00e9n, dirigidas a perfiles t\u00e9cnicos en crecimiento y con alta demanda en el mercado, como <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030279\/qgis-qfield-para-el-desarrollo-de-inventarios-de-campo-geolocalizados\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">herramientas de an\u00e1lisis territorial como QGIS<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><b>Idiomas para ampliar oportunidades<\/b><\/p>\n<p><span style=\"font-weight: 400\">La formaci\u00f3n en lenguas extranjeras contin\u00faa siendo otro de los pilares del programa, con cursos de iniciaci\u00f3n a idiomas como <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030291\/introduccion-al-japones\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">japon\u00e9s<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030256\/introduccion-al-coreano\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">coreano<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030283\/introduccion-al-chino\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">chino<\/span><\/a><span style=\"font-weight: 400\">, <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030091\/iniciacion-al-aleman-a1-1-mcer\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">alem\u00e1n<\/span><\/a><span style=\"font-weight: 400\">, o <\/span><a href=\"https:\/\/sede.fg.ull.es\/es\/curso\/detalle\/A26030282\/introduccion-al-griego-moderno\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">griego<\/span><\/a><span style=\"font-weight: 400\">, as\u00ed como preparatorios de ingl\u00e9s con acreditaci\u00f3n oficial en niveles B1 y B2.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Las personas interesadas pueden <\/span><b>acceder de manera gratuita<\/b><span style=\"font-weight: 400\"> si cumplen una serie de requisitos. Entre ellos, empadronamiento en Tenerife durante un a\u00f1o, inscripci\u00f3n en el Servicio Canario de Empleo como demandante o mejora de empleo y tener o estar estudiando una titulaci\u00f3n superior tanto universitaria como de formaci\u00f3n profesional.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Toda la informaci\u00f3n sobre el programa y el cat\u00e1logo completo se puede consultar a trav\u00e9s de la <\/span><a href=\"https:\/\/fg.ull.es\/empleo\/capacita\/formacion\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">p\u00e1gina web<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Capacita es un proyecto de empleo subvencionado por el Cabildo Insular de Tenerife para el apoyo a actividades en materia de empleo dentro del programa MEDI FDCAN, y gestionado por la Fundaci\u00f3n General de la Universidad de La Laguna.<\/span>[\/vc_column_text][vc_empty_space height=&#8221;24px&#8221;][vc_btn title=&#8221;Consulta el cat\u00e1logo completo de cursos&#8221; shape=&#8221;square&#8221; color=&#8221;warning&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-book&#8221; button_block=&#8221;true&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffg.ull.es%2Fempleo%2Fcapacita%2Fformacion%2F|target:_blank&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]El programa Capacita, impulsado por el Cabildo de Tenerife y la Universidad de La Laguna, a trav\u00e9s de su Fundaci\u00f3n General, refuerza su sexta edici\u00f3n con una ampliaci\u00f3n significativa de su cat\u00e1logo formativo para los pr\u00f3ximos meses. Capacita combina en un \u00fanico itinerario orientaci\u00f3n laboral, an\u00e1lisis personalizado de competencias y formaci\u00f3n especializada con el objetivo&#8230;<\/p>\n","protected":false},"author":47,"featured_media":60270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4,7],"tags":[],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2026\/05\/Noticia-Capacita-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/60269"}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=60269"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/60269\/revisions"}],"predecessor-version":[{"id":60271,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/60269\/revisions\/60271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/60270"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=60269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=60269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=60269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}