{"id":56606,"date":"2024-09-23T07:51:10","date_gmt":"2024-09-23T06:51:10","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=56606"},"modified":"2024-09-23T07:51:10","modified_gmt":"2024-09-23T06:51:10","slug":"la-welcoming-walk-una-actividad-para-el-senderismo-y-la-interculturalidad-en-tenerife","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2024\/09\/23\/la-welcoming-walk-una-actividad-para-el-senderismo-y-la-interculturalidad-en-tenerife\/","title":{"rendered":"La Welcoming Walk, una actividad para el senderismo y la interculturalidad en Tenerife"},"content":{"rendered":"<h3><b>El Observatorio de la Inmigraci\u00f3n de Tenerife celebra la Welcoming Walk, un recorrido circular de senderismo que muestra la interculturalidad y diversidad de La Laguna. En colaboraci\u00f3n con diversas entidades locales e internacionales, el evento ha demostrado ser un espacio clave para la convivencia y la reflexi\u00f3n intercultural, donde personas de diferentes nacionalidades comparten historias sobre la diversidad y la acogida, reforzando el senderismo como una herramienta poderosa para la inclusi\u00f3n social en la Isla.<\/b><\/h3>\n<p><span style=\"font-weight: 400\">El viernes 20 de septiembre se celebr\u00f3, con gran \u00e9xito, la Welcoming Walk, la IV edici\u00f3n del Pateo Intercultural, una actividad que reuni\u00f3 a m\u00e1s de 20 personas en una ruta de senderismo intercultural en la ciudad de La Laguna. Organizado por el Observatorio de la Inmigraci\u00f3n de Tenerife (OBITen), en colaboraci\u00f3n con la Fundaci\u00f3n General de la Universidad de La Laguna (FGULL), Anaga Fest, la Oficina de Voluntariado y Participaci\u00f3n Ambiental, el Ayuntamiento de San Crist\u00f3bal de La Laguna, el \u00c1rea de Medio Natural del Cabildo de Tenerife y la Federaci\u00f3n Tinerfe\u00f1a de Monta\u00f1ismo. Este evento se ha consolidado como un espacio de convivencia y reflexi\u00f3n, integrando a participantes de diversos or\u00edgenes culturales en un entorno natural y accesible.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Los participantes, con un rango de edad entre 19 y 79 a\u00f1os, pudieron disfrutar de una ruta circular que recorri\u00f3 la ciudad de La Laguna, pasando por el parque de Mesa Mota, mientras se realizaban paradas estrat\u00e9gicas para compartir la historia de la diversidad cultural de la zona y reflexionar sobre la acogida y la inclusi\u00f3n en la Isla. Este paseo, al igual que en sus ediciones anteriores, promovi\u00f3 el di\u00e1logo y la convivencia intercultural, reforzando el senderismo como herramienta de inclusi\u00f3n social. La actividad finaliz\u00f3 con un encuentro en el Servicio de Deportes de la Universidad de La Laguna (ULL), donde se cre\u00f3 un espacio de di\u00e1logo sobre la importancia del aprecio a la diversidad.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vicente Zapata Hern\u00e1ndez, profesor de Geograf\u00eda de la ULL y director de OBITen, as\u00ed como de la estrategia insular para la interculturalidad Juntas En la misma direcci\u00f3n, lider\u00f3 el trayecto y manifest\u00f3 que: \u201cEn los d\u00edas iniciales del curso acad\u00e9mico, tiene la m\u00e1xima importancia porque ampliamos la Jornada de Bienvenida al alumnado diverso que tenemos y procuramos espacios en los que se encuentran con la sociedad tinerfe\u00f1a, que tambi\u00e9n es muy diversa, y generamos una relaci\u00f3n, aparte de intercultural, intergeneracional\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La nueva estudiante del grado en Psicolog\u00eda de la ULL, Silke Johanna Kegel, declara que la creaci\u00f3n de este tipo de actividades es interesante porque \u201cahora s\u00e9 m\u00e1s sobre la ciudad y conozco a m\u00e1s personas. La historia y geograf\u00eda no las tengo en la universidad, y con esta actividad tengo la posibilidad de conocer m\u00e1s\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sebasti\u00e1n Gil Ramos, presidente de la Federaci\u00f3n Tinerfe\u00f1a de Monta\u00f1ismo, opina que: \u201cEl senderismo, en su concepto original, significa el conocimiento de los caminos y de la historia en torno a los mismos. Entonces, no hay ninguna diferenciaci\u00f3n entre la cultura y el deporte, en ese sentido, porque est\u00e1n integrados en una misma funci\u00f3n. Ojal\u00e1 pudi\u00e9ramos hacer estas actividades con mayor asiduidad, que no sea un d\u00eda al a\u00f1o, sino varias veces, porque as\u00ed transmitir\u00edamos m\u00e1s nuestros conocimientos al conjunto de la poblaci\u00f3n, y habr\u00eda mucha m\u00e1s integraci\u00f3n entre las diferentes comunidades que hoy en d\u00eda pasan por nuestra Isla. \u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Durante el recorrido, se habilitaron momentos de reflexi\u00f3n conjunta donde los participantes pudieron intercambiar ideas y experiencias sobre la acogida, el senderismo y el deporte como herramientas de inclusi\u00f3n social. Estos espacios permitieron crear un ambiente distendido y enriquecedor, donde se compartieron perspectivas diversas que contribuyeron a profundizar en la comprensi\u00f3n de la interculturalidad.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Adem\u00e1s, el evento estuvo vinculado al Proyecto SCORE, una iniciativa europea que lucha contra el racismo a trav\u00e9s del deporte. OBITen, como representante de Tenerife, incluy\u00f3 el Welcoming Walk dentro de las acciones del proyecto, demostrando una vez m\u00e1s el poder del deporte y el senderismo como herramientas de integraci\u00f3n y convivencia. El evento tambi\u00e9n form\u00f3 parte de la Welcoming Week (Semana de la Bienvenida Internacional), que se celebr\u00f3 del 13 al 20 de septiembre. Este evento global busca fomentar la acogida de personas migrantes y refugiadas, y Tenerife fue el \u00fanico territorio espa\u00f1ol en participar, junto a ciudades como Par\u00eds, Cracovia, y en M\u00e9xico, siendo uno de los pocos lugares no angl\u00f3fonos en formar parte de esta importante iniciativa.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Observatorio de la Inmigraci\u00f3n de Tenerife celebra la Welcoming Walk, un recorrido circular de senderismo que muestra la interculturalidad y diversidad de La Laguna. En colaboraci\u00f3n con diversas entidades locales e internacionales, el evento ha demostrado ser un espacio clave para la convivencia y la reflexi\u00f3n intercultural, donde personas de diferentes nacionalidades comparten historias&#8230;<\/p>\n","protected":false},"author":34,"featured_media":56607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,7],"tags":[820,186,722,67,822],"class_list":["post-56606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovacion","category-ultimas-noticias-portada-inicio","tag-convivencia-intercultural","tag-inmigracion","tag-intercultural","tag-obiten","tag-observatorio-de-la-inmigracion-de-tenerife-obiten"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2024\/09\/Welcoming-Walk-11-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/56606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=56606"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/56606\/revisions"}],"predecessor-version":[{"id":56608,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/56606\/revisions\/56608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/56607"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=56606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=56606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=56606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}