{"id":44762,"date":"2020-01-10T10:00:43","date_gmt":"2020-01-10T10:00:43","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=44762"},"modified":"2023-07-11T13:23:00","modified_gmt":"2023-07-11T12:23:00","slug":"alcance-organico-instagram","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2020\/01\/10\/alcance-organico-instagram\/","title":{"rendered":"C\u00f3mo contrarrestar la p\u00e9rdida de alcance org\u00e1nico en Instagram conociendo su algoritmo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h4><span style=\"font-weight: 400\">Como ya sabr\u00e1s, <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.instagram.com\/?hl=es\" target=\"_blank\" rel=\"noopener\">Instagram<\/a><\/span> es una empresa hermana de <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/es-es.facebook.com\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>,<\/span> la cual fue adquirida por <\/span><span style=\"font-weight: 400\">Mark Zuckerberg en 2012. Ambas redes sociales tienen sus propias plataformas publicitarias, las cuales suponen una v\u00eda de ingresos considerable para estos gigantes. Y la manera que tienen de incentivar la inversi\u00f3n por parte de las marcas en anuncios de pago es recortar el alcance org\u00e1nico (sin pagar) de las publicaciones.<\/span><\/h4>\n<p><span style=\"font-weight: 400\">Las nuevas generaciones est\u00e1n en Instagram y las empresas lo saben. Por eso, cada vez tienen mayor presencia en esta red social, y por ende, mayor necesidad de informaci\u00f3n fiable para afrontar una estrategia efectiva que les permita sortear las restricciones del algoritmo y amplificar su alcance org\u00e1nico en Instagram.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">El primer gran cambio del algoritmo fue en 2016, cuando <\/span><a href=\"https:\/\/instagram-press.com\/blog\/2016\/03\/15\/see-the-moments-you-care-about-first\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Instagram anunci\u00f3<\/span><\/a><span style=\"font-weight: 400\"> que \u201cel orden de las fotos y los videos en su feed se basar\u00e1 en la probabilidad de que est\u00e9 interesado en el contenido, su relaci\u00f3n con la persona que publica y la puntualidad de la publicaci\u00f3n\u201d. Se enterraba el orden cronol\u00f3gico inverso del feed para priorizar aquel contenido que Instagram entend\u00eda que m\u00e1s le interesaba a cada usuario con el objetivo de que el usuario pasara el mayor tiempo posible conectado a Instagram, y por ende, incrementar el n\u00famero de anuncios que el usuario pod\u00eda llegar a ver. A partir de este momento, la gente comenz\u00f3 a preguntarse qu\u00e9 se\u00f1ales permit\u00edan al algoritmo establecer que un contenido era relevante para un usuario.\u00a0<\/span><\/p>\n<h2><strong>Se\u00f1ales que premia el algoritmo de Instagram<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">Las tres se\u00f1ales en Instagram que permiten al algoritmo decidir sobre c\u00f3mo organizar el<a href=\"https:\/\/netzoe.com\/todos-2\/2017\/05\/como-tener-un-instagram-feed-perfecto\" target=\"_blank\" rel=\"noopener\"> feed<\/a> de un usuario son: relaci\u00f3n, inter\u00e9s y puntualidad.<\/span><\/p>\n<h3><strong>Relaci\u00f3n<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">El algoritmo favorece la visibilidad en tu feed del contenido de las cuentas con las que los usuarios interact\u00faan mucho. Por tanto, para incrementar el alcance de las publicaciones de tu cuenta deber\u00e1s lograr que la gente comente y converse entre s\u00ed. El env\u00edo de <a href=\"https:\/\/quiennomesigueeninstagram.com\/dm-instagram-mensajeria-directa\/\" target=\"_blank\" rel=\"noopener\">DM<\/a> y el etiquetado en las publicaciones son tambi\u00e9n se\u00f1ales fuertes de que existe una relaci\u00f3n de cercan\u00eda entre ambas cuentas, por lo que prioriza una visibilidad mutua.\u00a0<\/span><\/p>\n<h3><strong>Inter\u00e9s<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Si te gustan las fotos de mascotas o los v\u00eddeos de deportes extremos y sueles ver este tipo de contenido en Instagram, el algoritmo es capaz de sugerirte este tipo de contenidos y priorizarlos al principio de tu feed gracias al uso de tecnolog\u00eda de visi\u00f3n artificial que permite evaluar el contenido de una foto o v\u00eddeo y filtrarlo para las cuentas que hayan interactuado en el pasado con estos tipos de contenidos.<\/span><\/p>\n<h3><strong>Puntualidad<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Desde marzo de 2018, el algoritmo muestra los nuevos posts a los usuarios, por lo que hay que saber identificar los d\u00edas y horas en los que haya el mayor porcentaje posible de tu audiencia online. De esta manera, garantizas que el post tenga la mayor visibilidad org\u00e1nica posible.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/bit.ly\/3XiYeLM\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43474 size-full\" src=\"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5.jpg\" alt=\"\" width=\"2501\" height=\"855\" srcset=\"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5.jpg 2501w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-300x103.jpg 300w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-768x263.jpg 768w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-1024x350.jpg 1024w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-375x128.jpg 375w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-750x256.jpg 750w, https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/06\/CTAS_-5-1140x390.jpg 1140w\" sizes=\"auto, (max-width: 2501px) 100vw, 2501px\" \/><\/a><\/p>\n<h2><\/h2>\n<h2><strong>Recomendaciones para mejorar la visibilidad de tus publicaciones en Instagram<\/strong><\/h2>\n<p><span style=\"font-weight: 400\">A continuaci\u00f3n propongo algunos consejos y recomendaciones para mejorar la visibilidad en Instagram remando a favor del algoritmo.\u00a0<\/span><\/p>\n<h3><strong>Publicar de manera constante<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Si est\u00e1 en tu mano la posibilidad de aumentar la frecuencia de contenidos en Instagram, te recomiendo que lo hagas. Tal y como comentaba m\u00e1s arriba, gracias a la tecnolog\u00eda de visi\u00f3n artificial, si ofreces diferentes tipos de contenido, estos ser\u00e1n distribuidos entre tu audiencia de manera diversificada en funci\u00f3n de los intereses de cada usuario, por lo que no se percibir\u00e1 que has aumentado tu oferta de contenidos. Lo importante es que este incremento no sea a costa de mermar la calidad de las publicaciones.\u00a0<\/span><\/p>\n<h3><strong>Usar v\u00eddeos<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">El v\u00eddeo es el formato estrella. Los usuarios prefieren el v\u00eddeo a la foto, as\u00ed lo avala el crecimiento progresivo del consumo de este formato. M\u00e1s all\u00e1 de si el algoritmo lo privilegia o no, el v\u00eddeo logra aumentar el tiempo que pasa el usuario frente a tu <a href=\"https:\/\/www.vanesajackson.com\/post-en-instagram\/\" target=\"_blank\" rel=\"noopener\">post<\/a>, <a href=\"https:\/\/webescuela.com\/historias-instagram-stories\/\" target=\"_blank\" rel=\"noopener\">story<\/a> o directo, y eso redunda en el<a href=\"https:\/\/metricool.com\/es\/que-es-el-engagement-en-instagram-y-como-puede-ayudarte\/\" target=\"_blank\" rel=\"noopener\"> engagement<\/a>, lo que traslada se\u00f1ales positivas al algoritmo.<\/span><\/p>\n<h3><strong>Publicar cuando tu audiencia est\u00e9 online<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Esta recomendaci\u00f3n est\u00e1 vinculada a la se\u00f1al de puntualidad que coment\u00e1bamos arriba, como un factor positivo para el algoritmo. Consulta las estad\u00edsticas de tu cuenta de Instagram y programa la publicaci\u00f3n de tus contenidos con una herramienta como <a href=\"https:\/\/www.elgrupoinformatico.com\/como-programar-publicaciones-instagram-con-hootsuite-t41320.html\" target=\"_blank\" rel=\"noopener\">Hootsuite<\/a>, <a href=\"https:\/\/www.trecebits.com\/2019\/10\/07\/como-programar-stories-de-instagram-con-buffer\/\" target=\"_blank\" rel=\"noopener\">Buffer<\/a> o <a href=\"https:\/\/postcron.com\/es\/\" target=\"_blank\" rel=\"noopener\">Postcron<\/a> para asegurar la entrega del contenido en el momento en el que haya un mayor porcentaje de seguidores conectados.\u00a0<\/span><\/p>\n<h3><strong>Conversa e interact\u00faa con otras cuentas<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Si solo publicas y no interact\u00faas ni conversar con la comunidad en Instagram, olv\u00eddate. Las redes sociales son para conversar, para relacionarse. Pero construye relaciones aut\u00e9nticas. Conversa en las publicaciones de las cuentas que quieres que se fijen en ti y motiva a tus seguidores a que conversen contigo mediante el uso de preguntas.\u00a0<\/span><\/p>\n<h3><strong>Usa bien los hashtags<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Los<a href=\"https:\/\/metricool.com\/es\/hashtags-instagram-estrategias\/\" target=\"_blank\" rel=\"noopener\"> hashtags<\/a> son maravillosos porque permiten que nuestro contenido viaje m\u00e1s all\u00e1 de las fronteras de nuestros seguidores. Pero no abuses de ellos ni hagas un mal uso. Elige hashtags que se usen y que est\u00e9n vinculados a la tem\u00e1tica de tu contenido. Recuerda que puedes incluir hasta 30 hashtags en un post y hasta 10 en una story.\u00a0<\/span><\/p>\n<h3><strong>Haz un concurso de vez en cuando para darle un impulso a tu cuenta<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Una de las principales formas de darle un impulso al engagement de tu cuenta es sorteando algo en Instagram. Piensa en algo que le pueda interesar a tu audiencia y ofr\u00e9celo a cambio de que te sigan, comenten y le den me gusta a una publicaci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Y para terminar, recuerda en apoyarte en <\/span><a href=\"https:\/\/vilmanunez.com\/herramientas-instagram\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">herramientas que te ayuden a gestionar tu estrategia en Instagram<\/span><\/a><span style=\"font-weight: 400\">, desde editores de im\u00e1genes y buscadores de hashtags a programadores de contenidos y an\u00e1lisis de m\u00e9tricas.\u00a0<\/span><\/p>\n<h3>Consulta nuestras \u00faltimas entradas al <a href=\"http:\/\/bit.ly\/2I5PFQc\" target=\"_blank\" rel=\"noopener\">#BlogEmprende.ull<\/a><\/h3>\n<ul>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2018\/08\/17\/asesoramiento-para-emprender-con-metodo-emprendeull\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00bfNecesitas asesoramiento para emprender? Te contamos todo sobre el m\u00e9todo Emprende.ull<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2019\/01\/25\/emprender-con-discapacidad\/\" target=\"_blank\" rel=\"noopener\"><strong>Emprende con discapacidad<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2018\/11\/14\/crear-una-tienda-online-paso-a-paso\/\" target=\"_blank\" rel=\"noopener\"><b>Crear una tienda online paso a paso<\/b><\/a><\/li>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2018\/06\/14\/la-importancia-de-promover-la-cultura-emprendedora-en-las-nuevas-generaciones\/\" target=\"_blank\" rel=\"noopener\"><strong>La importancia de promover la cultura emprendedora en las nuevas generaciones<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2018\/04\/25\/finanzas-emprendedores-conceptos-cuenta-empezar\/\" target=\"_blank\" rel=\"noopener\"><strong>Finanzas para la comunidad emprendedora: conceptos a tener en cuenta antes de empezar<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/fg.ull.es\/noticias\/2018\/04\/11\/informacion-para-emprendedores-alcanzar-exito\/\" target=\"_blank\" rel=\"noopener\"><strong>Informaci\u00f3n para la comunidad emprendedora: lo que debes saber si quieres lograr el \u00e9xito de tu idea<\/strong><\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_btn title=\u00bb\u00bfNecesitas ayuda con tu proyecto emprendedor? \u00a1Pide cita!\u00bb color=\u00bbwarning\u00bb align=\u00bbcenter\u00bb link=\u00bburl:http%3A%2F%2Fbit.ly%2F3JcrLB1|target:_blank\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_single_image image=\u00bb44786&#8243; add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb style=\u00bbvc_box_circle_2&#8243;][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Como ya sabr\u00e1s, Instagram es una empresa hermana de Facebook, la cual fue adquirida por Mark Zuckerberg en 2012. Ambas redes sociales tienen sus propias plataformas publicitarias, las cuales suponen una v\u00eda de ingresos considerable para estos gigantes. Y la manera que tienen de incentivar la inversi\u00f3n por parte de las marcas en anuncios&#8230;<\/p>\n","protected":false},"author":10,"featured_media":44778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[374],"tags":[509,214,1132,1137],"class_list":["post-44762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emprende-ull","tag-emprendedoras","tag-emprendedores","tag-facebook","tag-instagram"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2020\/01\/media-998990_1920-300x218.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/44762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=44762"}],"version-history":[{"count":17,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/44762\/revisions"}],"predecessor-version":[{"id":54030,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/44762\/revisions\/54030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/44778"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=44762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=44762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=44762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}