{"id":42096,"date":"2019-05-22T15:45:54","date_gmt":"2019-05-22T14:45:54","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=42096"},"modified":"2019-05-22T15:45:54","modified_gmt":"2019-05-22T14:45:54","slug":"13-ideas-de-negocio-del-proyecto-idealo-estaran-presentes-en-la-feria-del-talento-emprendedor-de-la-universidad-de-la-laguna","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2019\/05\/22\/13-ideas-de-negocio-del-proyecto-idealo-estaran-presentes-en-la-feria-del-talento-emprendedor-de-la-universidad-de-la-laguna\/","title":{"rendered":"13 ideas de negocio del Proyecto Id\u00e9alo estar\u00e1n presentes en la `Feria del Talento Emprendedor de la Universidad de La Laguna\u00b4"},"content":{"rendered":"<h3>La<em> Muestra de ideas de negocio<\/em> de la segunda edici\u00f3n del proyecto educativo Id\u00e9alo 19 tendr\u00e1 lugar el pr\u00f3ximo viernes, 24 de mayo, en el hall central de la Facultad de Econom\u00eda, Empresa y Turismo; se enmarca en la VII edici\u00f3n de la <strong>Feria del Talento Emprendedor<\/strong>. Un acto organizado por el Vicerrectorado de Relaciones con la Sociedad a trav\u00e9s de su c\u00e1tedra <strong>Fundaci\u00f3n Disa<\/strong> de j\u00f3venes emprendedores y en colaboraci\u00f3n con la <strong>Consejer\u00eda de Educaci\u00f3n del Gobierno de Canarias<\/strong>.<\/h3>\n<p>De un total de <strong>143 v\u00eddeos presentados<\/strong> al proyecto Id\u00e9alo 19, <strong>trece de ellos<\/strong> participaran en este foro. Se trata de ideas de negocio innovadoras, desarrolladas por equipos de estudiantes de Secundaria, Bachillerato y Formaci\u00f3n Profesional de la isla de Tenerife.<\/p>\n<p>A trav\u00e9s de esta Muestra, los participantes seleccionados tendr\u00e1n la oportunidad de mostrar y explicar al p\u00fablico, de forma directa, sus ideas mediante un ordenador y unos cascos. Tambi\u00e9n, podr\u00e1n llevar otros materiales de difusi\u00f3n relacionados con su propuesta, con el objetivo de captar la m\u00e1xima atenci\u00f3n posible del p\u00fablico asistente. As\u00ed, durante la jornada, podr\u00e1n percibir el impacto que generan sus propuestas en el p\u00fablico y valorar realmente la viabilidad de la idea.<\/p>\n<p>La valoraci\u00f3n de v\u00eddeos para aspirar a la participaci\u00f3n en la Muestra, se realiz\u00f3 de la mano de un comit\u00e9 de catorce personas expertas en el \u00e1mbito del emprendimiento, la educaci\u00f3n y el mundo audiovisual. La clasificaci\u00f3n de proyectos finalistas qued\u00f3 de esta forma: seis proyectos de E.S.O, tres proyectos de Bachillerato, otros 3 de Formaci\u00f3n Profesional y, por \u00faltimo, una iniciativa elegida por votaci\u00f3n del p\u00fablico a trav\u00e9s del <a href=\"https:\/\/www.youtube.com\/watch?v=U_7JkFsfgHU&amp;list=PLbU1uwxBUAGFWzqHdvP_NJwH-pQ5r6AJJ\" target=\"_blank\" rel=\"noopener\"><strong>canal de Youtube de la Fundaci\u00f3n General universitaria<\/strong>.<\/a><\/p>\n<p><em>Id\u00e9alo<\/em> promueve el trabajo en equipo, fomenta el esp\u00edritu emprendedor y estimula la creatividad; ha contado con talleres de creaci\u00f3n de v\u00eddeo para que el alumnado pudiera trabajar aspectos como el estilo gr\u00e1fico, la b\u00fasqueda de recursos audiovisuales, el <em>storyboard<\/em> o la grabaci\u00f3n y edici\u00f3n de v\u00eddeo. Se realizaron un total de 22 talleres donde participaron m\u00e1s de 750 estudiantes.<\/p>\n<p>Este proyecto educativo es promovido por la Fundaci\u00f3n General Universidad de La Laguna a trav\u00e9s de su servicio gratuito de emprendimiento y consolidaci\u00f3n empresarial. En esta edici\u00f3n, colaboran, por un lado, Fundaci\u00f3n Disa, para el desarrollo del proyecto \u2018Id\u00e9alo\u2019 en la isla y, por otro, el Ayuntamiento de Arona, entidad encargada de llevar a cabo el programa por el municipio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Muestra de ideas de negocio de la segunda edici\u00f3n del proyecto educativo Id\u00e9alo 19 tendr\u00e1 lugar el pr\u00f3ximo viernes 24 de mayo.<\/p>\n","protected":false},"author":3,"featured_media":42097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[374,278,4,7],"tags":[654,281],"class_list":["post-42096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emprende-ull","category-emprendimiento","category-noticia-principal","category-ultimas-noticias-portada-inicio","tag-catedra-de-jovenes-emprendedores-de-la-ull","tag-idealo"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/05\/BANNER-FGULL-300x169.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/42096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=42096"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/42096\/revisions"}],"predecessor-version":[{"id":42098,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/42096\/revisions\/42098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/42097"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=42096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=42096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=42096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}