{"id":41238,"date":"2019-03-19T10:30:59","date_gmt":"2019-03-19T10:30:59","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=41238"},"modified":"2019-03-19T14:42:30","modified_gmt":"2019-03-19T14:42:30","slug":"coloquio-comunicacion-teresa-baro","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2019\/03\/19\/coloquio-comunicacion-teresa-baro\/","title":{"rendered":"Teresa Bar\u00f3 realizar\u00e1 una conferencia sobre \u201cEl Arte de Comunicar para el \u00c9xito Profesional\u201d"},"content":{"rendered":"<h3>El sal\u00f3n de actos del edificio de Ciencias de la Comunicaci\u00f3n de la ULL ser\u00e1 la sede de esta actividad. Se celebrar\u00e1 el 29 de marzo de 12:00 a 13:30 horas y forma parte de la serie de charlas \u00abTalent &amp; Jobs\u00bb promovidas por la Fundaci\u00f3n CajaCanarias.<\/h3>\n<p>La <strong>Universidad de La Laguna<\/strong> y <strong>CajaCanarias<\/strong> organizan\u00a0una sesi\u00f3n que se llevar\u00e1 a cabo en el edificio de La Pir\u00e1mide. En esta jornada, se podr\u00e1 aprender sobre la <strong><a href=\"http:\/\/forotalentandjob.es\/portfolio-item\/el-arte-de-comunicar\/\" target=\"_blank\" rel=\"noopener\">importancia de la comunicaci\u00f3n<\/a><\/strong> en el \u00e1mbito personal y profesional. Los asistentes tendr\u00e1n la ocasi\u00f3n de ver c\u00f3mo las formas de expresi\u00f3n influyen en los resultados de sus objetivos y metas.<\/p>\n<p>Durante esta actividad, los participantes tendr\u00e1n la oportunidad de aprender junto a <a href=\"https:\/\/www.teresabaro.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Teresa Bar\u00f3<\/strong><\/a>, emprendedora y empresaria. Con una gran experiencia en el mundo de la comunicaci\u00f3n, la ponente de esa jornada compartir\u00e1 sus conocimientos para ayudar a los asistentes a <strong>superar sus dificultades comunicativas<\/strong>. As\u00ed, podr\u00e1n conocer t\u00e9cnicas para aumentar la confianza en s\u00ed mismos, ganar seguridad en el momento de hablar y superar la timidez.<\/p>\n<p>El objetivo de esta conferencia es que los participantes sean conscientes de que las habilidades comunicativas son un factor clave para conseguir sus prop\u00f3sitos, tanto a nivel particular como profesional. Por lo tanto, una comunicaci\u00f3n efectiva servir\u00e1 para una superaci\u00f3n personal y, adem\u00e1s, como elemento diferenciador a la hora de competir en el mundo laboral.<\/p>\n<p><strong>TERESA BAR\u00d3<\/strong><\/p>\n<p>Teresa Bar\u00f3 es formadora experta en Habilidades de Comunicaci\u00f3n. Actualmente es directora de la Consultor\u00eda Verbal no Verbal. Asimismo, es autora de diversos libros sobre comunicaci\u00f3n a trav\u00e9s de los que comparte sus conocimientos en este \u00e1mbito.<\/p>\n<p>Adem\u00e1s, imparte cursos de formaci\u00f3n de car\u00e1cter presencial y online para ayudar a personas y empresas a superar sus carencias a la hora de transmitir informaci\u00f3n, y as\u00ed conseguir una comunicaci\u00f3n efectiva. De esta manera, ha formado y ayudado a muchos profesionales e instituciones de distintos sectores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teresa Bar\u00f3 realizar\u00e1 un coloquio sobre \u201cEl Arte de Comunicar para el \u00c9xito Profesional\u201d<\/p>\n","protected":false},"author":26,"featured_media":41240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1157,6,7],"tags":[900,337,901],"class_list":["post-41238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-borrar-sin-categorizar","category-formacion","category-ultimas-noticias-portada-inicio","tag-coloquio","tag-comunicacion","tag-teresa-baro"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2019\/03\/unnamed-1-300x254.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/41238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=41238"}],"version-history":[{"count":5,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/41238\/revisions"}],"predecessor-version":[{"id":41247,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/41238\/revisions\/41247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/41240"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=41238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=41238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=41238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}