{"id":37285,"date":"2018-06-07T13:37:41","date_gmt":"2018-06-07T12:37:41","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=37285"},"modified":"2018-06-11T14:23:07","modified_gmt":"2018-06-11T13:23:07","slug":"el-curso-gratuito-inventalo-amplia-su-periodo-de-inscripcion","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2018\/06\/07\/el-curso-gratuito-inventalo-amplia-su-periodo-de-inscripcion\/","title":{"rendered":"El curso gratuito Inv\u00e9ntalo! ampl\u00eda su periodo de inscripci\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<strong><em>Inv\u00e9ntalo!<\/em> es un curso online y gratuito destinado al alumnado de doctorado y m\u00e1ster de la Universidad de La Laguna interesado en formarse en emprendimiento.<\/strong><\/p>\n<p><em><a href=\"https:\/\/fg.ull.es\/empleo\/curso-online-inventalo\/\" target=\"_blank\" rel=\"noopener\">Inv\u00e9ntalo<\/a>!<\/em>\u00a0ampl\u00eda su periodo de inscripci\u00f3n hasta el 10 de junio. El curso online especializado en emprendimiento tendr\u00e1 lugar del 11 de junio al 1 de julio. Se trata de una formaci\u00f3n eminentemente pr\u00e1ctica que buscar\u00e1 formar a trav\u00e9s del emprendimiento \u00e1gil al alumnado.<\/p>\n<p>El curso est\u00e1 especialmente destinado al alumnado de doctorado y m\u00e1ster de la Universidad de La Laguna interesado en formarse en emprendimiento. No es necesaria la formaci\u00f3n previa en emprendimiento para matricularse.<\/p>\n<p>Cuenta con 25 horas de duraci\u00f3n durante las que el personal docente impartir\u00e1 lecciones sobre c\u00f3mo crear proyectos empresariales validando hip\u00f3tesis a trav\u00e9s de las metodolog\u00edas como el emprendimiento \u00e1gil o el m\u00e9todo cient\u00edfico.<\/p>\n<p><em>Inv\u00e9ntalo!<\/em> se trata de un curso gratuito que cuenta con el desarrollo de la Fundaci\u00f3n General de la Universidad de La Laguna y la financiaci\u00f3n del Servicio Canario de Empleo del Gobierno de Canarias.[\/vc_column_text][vc_btn title=\u00bbINSCRIPCI\u00d3N\u00bb color=\u00bbviolet\u00bb link=\u00bburl:https%3A%2F%2Fdocs.google.com%2Fforms%2Fd%2Fe%2F1FAIpQLSfHyPkzy-GUvucY85R3Qwwib8AeQnzKmpq6OZXU7fx28vmNHg%2Fviewform||target:%20_blank|\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Inv\u00e9ntalo! es un curso online y gratuito destinado al alumnado de doctorado y m\u00e1ster de la Universidad de La Laguna interesado en formarse en emprendimiento. Inv\u00e9ntalo!\u00a0ampl\u00eda su periodo de inscripci\u00f3n hasta el 10 de junio. El curso online especializado en emprendimiento tendr\u00e1 lugar del 11 de junio al 1 de julio. Se trata de una&#8230;<\/p>\n","protected":false},"author":9,"featured_media":37286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278],"tags":[454],"class_list":["post-37285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprendimiento","tag-inventalo"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/pantalla_1920x1080px-1-1-300x169.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=37285"}],"version-history":[{"count":3,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37285\/revisions"}],"predecessor-version":[{"id":37289,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37285\/revisions\/37289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/37286"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=37285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=37285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=37285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}