{"id":37237,"date":"2018-06-05T14:05:58","date_gmt":"2018-06-05T13:05:58","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=37237"},"modified":"2023-03-24T10:29:46","modified_gmt":"2023-03-24T10:29:46","slug":"las-cooperativas-escolares-terminaran-el-curso-con-su-acto-solidario-liquida-y-comparte","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2018\/06\/05\/las-cooperativas-escolares-terminaran-el-curso-con-su-acto-solidario-liquida-y-comparte\/","title":{"rendered":"Las cooperativas escolares terminar\u00e1n el curso con su acto solidario: &#8216;Liquida y comparte&#8217;"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<strong>M\u00e1s de 1400 ni\u00f1os y ni\u00f1as de 41 centros educativos distintos han participado en la octava edici\u00f3n de \u2018Ense\u00f1ar para Emprender\u2019, el proyecto que fomenta la cultura emprendedora en el alumnado m\u00e1s joven.<\/strong><\/p>\n<p><strong>El broche final del proyecto tendr\u00e1 lugar el pr\u00f3ximo 12 de junio en el Paraninfo de la ULL con la simulaci\u00f3n de la \u201cliquidaci\u00f3n de cuentas\u201d y la entrega de donativos a diversas ONG\u00b4s.<\/strong><\/p>\n<p>El pr\u00f3ximo martes, 12 de junio, tendr\u00e1 lugar el \u00faltimo acto de la presente edici\u00f3n de <em>Ense\u00f1ar Para Emprender,<\/em> un proyecto de fomento de la actitud emprendedora que se ha desarrollado a lo largo del curso escolar por m\u00e1s de 1400 escolares de la isla de Tenerife; este acto se denomina <em>Liquida y comparte<\/em> y se centra en la resoluci\u00f3n de las <em>finanzas<\/em> de las cooperativas, que donar\u00e1n parte de sus ingresos obtenidos en las Ferias de Cooperativas Escolares, a diversas ONGs de su elecci\u00f3n.<\/p>\n<p><em>Ense\u00f1ar para Emprender<\/em> es un proyecto con ocho a\u00f1os de trayectoria. El objetivo de la iniciativa es que el alumnado participante pueda aprender habilidades b\u00e1sicas relacionadas con el emprendimiento desde edades tempranas. Durante el curso han participado en diversas actividades para crear y mejorar sus cooperativas escolares, aprendiendo de forma l\u00fadica e interactiva c\u00f3mo funciona la creaci\u00f3n de un negocio, la b\u00fasqueda de financiaci\u00f3n o la creatividad publicitaria.<\/p>\n<p>Tras ocho a\u00f1os, la implicaci\u00f3n de los colegios se ha consolidado. A modo de ejemplo, este a\u00f1o el centro Hogar Escuela Mar\u00eda Auxiliadora ha batido r\u00e9cords de participaci\u00f3n, tomando parte todos los ni\u00f1os del mismo con doce cooperativas escolares, dos por curso.<\/p>\n<p>Durante el curso, los escolares han tenido que fabricar sus productos, la mayor parte con materiales reciclados, y han tenido que ir superando las diferentes fases que componen la acci\u00f3n de una cooperativa: decidir sobre los cargos de representaci\u00f3n, decidir la forma de organizarse, preparar unos estatutos, solicitar el permiso de venta etc. Con estas acciones se pretende que el alumnado pueda acercarse a valores como el trabajo cooperativo, el compa\u00f1erismo, la responsabilidad, el respeto al medio ambiente, la sostenibilidad, la solidaridad o la superaci\u00f3n personal.<\/p>\n<p>Todo ese esfuerzo se vio reflejado en los dos grandes actos del proyecto: las Ferias de Cooperativas Escolares. Se celebraron dos, una en el municipio de San Crist\u00f3bal de La Laguna y otra en el municipio de Candelaria. En total participaron m\u00e1s de 1400 ni\u00f1os y ni\u00f1as de 41 centros educativos distintos que conformaron 68 cooperativas escolares.<\/p>\n<p>En esta edici\u00f3n ha aumentado, por segundo a\u00f1o consecutivo, la participaci\u00f3n del alumnado de Educaci\u00f3n Especial, 132 personas participantes de ocho aulas enclave y de tres centros distintos.<\/p>\n<p>Por otra parte, se ha incrementado la participaci\u00f3n del voluntariado en las acciones del proyecto, con diecisiete personas, algunos estudiantes de la Universidad de La Laguna, apoyando la organizaci\u00f3n de las Ferias de Cooperativas Escolares.<\/p>\n<p>El proyecto tambi\u00e9n ha contado con la colaboraci\u00f3n por parte de las familias, tanto en el aula como en eventos externos como la Feria, permiso de venta y acto de <em>Liquida y comparte<\/em>, fomentando y enriqueciendo as\u00ed los v\u00ednculos familiares.<\/p>\n<p><em>Ense\u00f1ar para emprender<\/em>\u00a0es un proyecto gestionado por la Universidad de La Laguna, a trav\u00e9s de su Fundaci\u00f3n General, en colaboraci\u00f3n de la Consejer\u00eda de Educaci\u00f3n del Gobierno de Canarias y Cajasiete.\u00a0Las Ferias de Cooperativas Escolares en San Crist\u00f3bal de La Laguna y Candelaria han sido financiadas por el Ayuntamiento de La Laguna y el Ayuntamiento de Candelaria respectivamente. El acto <em>Liquida y comparte<\/em> lo financia C\u00e1tedra Cajasiete de Econom\u00eda Social y Cooperativa de la Universidad de La Laguna y la Cooperativa de Cr\u00e9dito Cajasiete.[\/vc_column_text][vc_cta h2=\u00bbLIQUIDA Y COMPARTE\u00bb]<em>Liquida y Comparte<\/em> es la actividad que cierra el proyecto <em>Ense\u00f1ar para Emprender<\/em> y funciona como acto simb\u00f3lico sobre el balance de cuentas realizado por las cooperativas. Tendr\u00e1 lugar el 12 de junio en las instalaciones del Paraninfo de la Universidad de La Laguna, a partir de las 10 horas.<\/p>\n<p>Consiste en un acto solidario en el que las cooperativas escolares participantes donan parte de sus ingresos obtenidos en las Ferias de Cooperativas Escolares a diversas entidades sin \u00e1nimo de lucro que el propio alumnado ha elegido.[\/vc_cta][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]M\u00e1s de 1400 ni\u00f1os y ni\u00f1as de 41 centros educativos distintos han participado en la octava edici\u00f3n de \u2018Ense\u00f1ar para Emprender\u2019, el proyecto que fomenta la cultura emprendedora en el alumnado m\u00e1s joven. El broche final del proyecto tendr\u00e1 lugar el pr\u00f3ximo 12 de junio en el Paraninfo de la ULL con la simulaci\u00f3n de&#8230;<\/p>\n","protected":false},"author":9,"featured_media":37238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,1411],"tags":[40,172],"class_list":["post-37237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprendimiento","category-ensenar-para-emprender","tag-ensenar-para-emprender","tag-liquida-y-comparte"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2018\/06\/FCE-La-Laguna_01-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=37237"}],"version-history":[{"count":3,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37237\/revisions"}],"predecessor-version":[{"id":37260,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37237\/revisions\/37260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/37238"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=37237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=37237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=37237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}