{"id":37072,"date":"2018-05-25T09:53:30","date_gmt":"2018-05-25T08:53:30","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=37072"},"modified":"2018-05-25T09:53:30","modified_gmt":"2018-05-25T08:53:30","slug":"la-universidad-de-la-laguna-acogio-el-acto-de-entrega-de-los-premios-crea-y-recicla-2018","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2018\/05\/25\/la-universidad-de-la-laguna-acogio-el-acto-de-entrega-de-los-premios-crea-y-recicla-2018\/","title":{"rendered":"La Universidad de La Laguna acogi\u00f3 el acto de entrega de los premios Crea y Recicla 2018"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space][vc_video link=\u00bbhttp:\/\/www.facebook.com\/CatedraSostenibilidadULL\/videos\/173534816666321\/\u00bb][vc_empty_space][vc_column_text]La Universidad de La Laguna, a trav\u00e9s de su\u00a0<a href=\"https:\/\/www.facebook.com\/CatedraSostenibilidadULL\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\" rel=\"noopener\">C\u00e1tedra de Medio Ambiente y Desarrollo Sostenible Cabildo de Tenerife<\/a>, acogi\u00f3 recientemente el acto de entrega de la IV Edici\u00f3n de los Premios Crea y Recicla 2018, celebrado en la Secci\u00f3n de Periodismo de la Facultad de Ciencias Pol\u00edticas, Sociales y de la Comunicaci\u00f3n.<\/p>\n<p>El objetivo del premio es fomentar y reconocer el talento emprendedor de los j\u00f3venes, en proyectos relacionados con la gesti\u00f3n de residuos y la econom\u00eda circular. Es una iniciativa del Gobierno de Canarias, Ecoembes, los siete cabildos insulares, las dos universidades p\u00fablicas de Canarias y sus respectivas fundaciones, gestionada por la Fundaci\u00f3n Canarias Recicla.<\/p>\n<p>La gala cont\u00f3 con la actuaci\u00f3n del m\u00fasico y actor Abraham G\u00f3mez Rosales, y ocnt\u00f3 con la representaci\u00f3n institucional del director de la \u00b4catedra convocante, Carlos Jim\u00e9nez; la Viceconsejera de Medio Ambiente del Gobierno de Canarias, Blanca Delia P\u00e9rez Delgado; la directora de Gesti\u00f3n Local y Auton\u00f3mica de Ecoembes, Carlota Cruz Izquierdo; la presidenta de la Fundaci\u00f3n Canarias Recicla, M\u00aa Jos\u00e9 Rosa; el director gerente de la Fundaci\u00f3n Universitaria ULL, Julio Brito Santana; y la coordinadora de proyectos ambientales de la Fundaci\u00f3n Canarias Recicla J\u00e9sica C\u00e1mara, quien ley\u00f3 el acta del jurado.<\/p>\n<p>[\/vc_column_text][vc_cta h2=\u00bbGANADORES\u00bb color=\u00bbviolet\u00bb]Los proyectos ganadores por la provincia de Santa Cruz de Tenerife para Mar\u00eda Fernanda Sapino, estudiante de 4\u00ba del Grado en Dise\u00f1o, por el\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/1110NxYM0NEI7kf-dRqr6_Ylfqqo8jkXT\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">proyecto Rabo Gato<\/a>, en la primera posici\u00f3n.<\/p>\n<p>El segundo clasificado fue Sa\u00edn Josu\u00e9 Cabrera, de la Facultad de Ingenier\u00eda Civil, por el proyecto\u00a0<em>Un progreso dotado de ventajas<\/em>, mientras que en tercer lugar qued\u00f3 Rom\u00e9n Gonz\u00e1lez Cabrera, de la Facultad de Geograf\u00eda e Historia, por la iniciativa Green Island.[\/vc_cta][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space][vc_video link=\u00bbhttp:\/\/www.facebook.com\/CatedraSostenibilidadULL\/videos\/173534816666321\/\u00bb][vc_empty_space][vc_column_text]La Universidad de La Laguna, a trav\u00e9s de su\u00a0C\u00e1tedra de Medio Ambiente y Desarrollo Sostenible Cabildo de Tenerife, acogi\u00f3 recientemente el acto de entrega de la IV Edici\u00f3n de los Premios Crea y Recicla 2018, celebrado en la Secci\u00f3n de Periodismo de la Facultad de Ciencias Pol\u00edticas, Sociales y de la Comunicaci\u00f3n. El objetivo&#8230;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1157],"tags":[],"class_list":["post-37072","post","type-post","status-publish","format-standard","hentry","category-borrar-sin-categorizar"],"featured_image_thumbnail_url":"","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=37072"}],"version-history":[{"count":5,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37072\/revisions"}],"predecessor-version":[{"id":37077,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/37072\/revisions\/37077"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=37072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=37072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=37072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}