{"id":36191,"date":"2018-04-02T13:26:39","date_gmt":"2018-04-02T12:26:39","guid":{"rendered":"https:\/\/fg.ull.es\/noticias\/?p=36191"},"modified":"2023-03-24T10:28:21","modified_gmt":"2023-03-24T10:28:21","slug":"equipo-tecnico-visitas-centros-escolares","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2018\/04\/02\/equipo-tecnico-visitas-centros-escolares\/","title":{"rendered":"Contin\u00faan las visitas a los centros escolares dentro de \u00abEnse\u00f1ar Para Emprender\u00bb"},"content":{"rendered":"<p><strong>El equipo t\u00e9cnico centr\u00f3 las \u00faltimas actividades en el apoyo de aspectos del programa formativo como la solicitud del n\u00famero CIF.<\/strong><\/p>\n<p>El equipo t\u00e9cnico del \u00e1rea de emprendimiento de la Fundaci\u00f3n General de la Universidad de La Laguna contin\u00faa con <a href=\"https:\/\/fg.ull.es\/noticias\/2018\/03\/13\/equipo-tecnico-fundacion-general-desarrollo-empresarial-visitas-epe\/\" target=\"_blank\" rel=\"noopener\">las visitas organizadas en el marco del proyecto Ense\u00f1ar para Emprender (EPE).<\/a> En las \u00faltimas semanas han visitado a los centros educativos CPEE ACAMAN, CEIP Princesa Tejina, IES Dr. Antonio Gonz\u00e1lez Gonz\u00e1lez y el CPEIPS Hispano Brit\u00e1nico.<\/p>\n<p>Durante las jornadas, el equipo t\u00e9cnico se ha centrado en la explicaci\u00f3n de una serie de cuestiones clave del programa formativo, especialmente en la solicitud del n\u00famero CIF. \u00a0Adem\u00e1s, algunas de las cooperativas mostraron sus talleres y los productos que est\u00e1n fabricando.<\/p>\n<p>EPE es un proyecto centrado en el desarrollo del aprendizaje creativo y emprendedor del alumnado de distintos centros escolares de Educaci\u00f3n Infantil, Educaci\u00f3n Primaria y Educaci\u00f3n Especial de Tenerife. De manera l\u00fadica, el objetivo est\u00e1 en que puedan aprender sobre valores como el trabajo en equipo, la toma de decisiones, resoluci\u00f3n de conflictos, el compa\u00f1erismo, la solidaridad o la superaci\u00f3n personal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo t\u00e9cnico centr\u00f3 las \u00faltimas actividades en el apoyo de aspectos del programa formativo como la solicitud del n\u00famero CIF. El equipo t\u00e9cnico del \u00e1rea de emprendimiento de la Fundaci\u00f3n General de la Universidad de La Laguna contin\u00faa con las visitas organizadas en el marco del proyecto Ense\u00f1ar para Emprender (EPE). En las \u00faltimas&#8230;<\/p>\n","protected":false},"author":9,"featured_media":36192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,1411],"tags":[37,40],"class_list":["post-36191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprendimiento","category-ensenar-para-emprender","tag-cooperativas-escolares","tag-ensenar-para-emprender"],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2018\/04\/Colegio-Hispano-Brit\u00e1nico-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/36191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=36191"}],"version-history":[{"count":3,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/36191\/revisions"}],"predecessor-version":[{"id":36216,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/36191\/revisions\/36216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/36192"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=36191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=36191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=36191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}