{"id":33279,"date":"2017-07-24T14:30:34","date_gmt":"2017-07-24T13:30:34","guid":{"rendered":"https:\/\/www.fg.ull.es\/?p=33279\/"},"modified":"2017-12-05T10:27:49","modified_gmt":"2017-12-05T10:27:49","slug":"acuerdo-de-colaboracion-con-la-empresa-de-asesoramiento-a-startups-loogic","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2017\/07\/24\/acuerdo-de-colaboracion-con-la-empresa-de-asesoramiento-a-startups-loogic\/","title":{"rendered":"Acuerdo de colaboraci\u00f3n con la empresa de asesoramiento a startups Loogic"},"content":{"rendered":"<h1><b>Acuerdo de colaboraci\u00f3n entre la Fundaci\u00f3n General Universitaria y Loogic<\/b><\/h1>\n<h4><span style=\"font-weight: 400\">Gracias a este convenio se podr\u00e1n realizar acciones de asesoramiento que se enmarcan dentro del Plan de Empleo para la Educaci\u00f3n Superior que se gestionan gracias a la Universidad de La L<\/span><span style=\"font-weight: 400\">aguna<\/span><span style=\"font-weight: 400\">\u00a0y se subvencionan por medio del Servicio Canario de Empleo<\/span><i><span style=\"font-weight: 400\">.<\/span><\/i><\/h4>\n<p><span style=\"font-weight: 400\">La empresa <\/span><a href=\"https:\/\/loogic.com\/\"><span style=\"font-weight: 400\">Loogic<\/span><\/a><span style=\"font-weight: 400\"> cierra un principio de acuerdo para colaborar en el asesoramiento espec\u00edfico sobre financiaci\u00f3n para startups (Business Angels, Capital Riesgo, Crowdfunding y Equitycrowdfunding). Un acuerdo fundamental para cumplir con varios pilares del Programa por Cuenta Propia del Plan de Empleo para la Educaci\u00f3n Superior como son el asesoramiento espec\u00edfico de creaci\u00f3n de empresas y el apoyo a proyectos en fase de consolidaci\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Desde su fundaci\u00f3n en 2003 Loogic se ha convertido en el medio de informaci\u00f3n de referencia para emprendedores y startups del mundo de la tecnolog\u00eda y la innovaci\u00f3n en Espa\u00f1a y Am\u00e9rica Latina. Javier Mart\u00edn e Ignacio de Miguel son sus promotores iniciales, a los que m\u00e1s adelante se han unido otros emprendedores como Agust\u00edn Cuenca, Mariano Torrecilla y Javier Esteban, para la puesta en marcha de iniciativas como Smart Money, el evento en el que se ponen en contacto inversores con emprendedores y tambi\u00e9n Loogic Ventures el servicio de asesoramiento en la b\u00fasqueda de inversi\u00f3n para startups.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Esta colaboraci\u00f3n surge por la necesidad de lograr un primer asesoramiento acorde con las etapas iniciales de creaci\u00f3n de proyectos, es decir, aquellos que presentan potencialmente un alto impacto, pero que se encuentran en fases muy tempranas de definici\u00f3n de modelos de negocio. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Para solicitar este asesoramiento individual y propio, se puede gestionar a trav\u00e9s de la web del <strong><a href=\"https:\/\/fg.ull.es\/empleo\/planempleo\/\">Plan de Empleo para la Educaci\u00f3n Superior<\/a>.<\/strong><\/span><\/p>\n<h4><strong>\u00a0<\/strong><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a este convenio se podr\u00e1n realizar acciones de asesoramiento que se enmarcan dentro del Plan de Empleo para la Educaci\u00f3n Superior que se gestionan gracias a la Universidad de La Laguna\u00a0y se subvencionan por medio del Servicio Canario de Empleo<\/p>\n","protected":false},"author":3,"featured_media":33312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[64],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2017\/07\/loogic_272x90.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33279"}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=33279"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33279\/revisions"}],"predecessor-version":[{"id":34811,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33279\/revisions\/34811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/33312"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=33279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=33279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=33279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}