{"id":33218,"date":"2017-07-13T13:29:57","date_gmt":"2017-07-13T12:29:57","guid":{"rendered":"https:\/\/www.fg.ull.es\/?p=33218\/"},"modified":"2017-08-02T11:17:08","modified_gmt":"2017-08-02T11:17:08","slug":"la-ii-edicion-de-captura-tu-idea-ya-tiene-sus-iniciativas-ganadoras","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2017\/07\/13\/la-ii-edicion-de-captura-tu-idea-ya-tiene-sus-iniciativas-ganadoras\/","title":{"rendered":"La II Edici\u00f3n de &#8220;Captura tu Idea&#8221; ya tiene sus iniciativas ganadoras"},"content":{"rendered":"<h1>La II Edici\u00f3n de &#8220;Captura tu Idea&#8221; ya tiene sus iniciativas ganadoras<\/h1>\n<h4>El pasado 30 de junio cerr\u00f3 el plazo votaci\u00f3n de las propuestas registradas en la web oficial de la II Edici\u00f3n de \u201cCaptura tu Idea\u201d. Una iniciativa que busca potenciar la creatividad y el esp\u00edritu emprendedor en el entorno lagunero. La entrega de premios se realizar\u00e1 el 19 de julio en el Paraninfo de la Universidad, a partir de las 19 horas. De las 72 ideas registradas, cuatro de ellas han sido las ganadoras de esta \u00a0II Edici\u00f3n. El premio es un dispositivo m\u00f3vil Aquaris X5 Plus.<\/h4>\n<p><a href=\"https:\/\/www.capturatuidea.com\/?p=934\"><strong>\u00a0\u201cApp Incidencias y Cuestiones\u201d<\/strong><\/a> es la iniciativa <strong>que m\u00e1s votos obtuvo por parte del p\u00fablico<\/strong>. Su autora, Elena Flores, destaca que: \u201cEn la ciudad de La Laguna, muchas veces encontramos desperfectos en las calles, bancos rotos, se\u00f1ales de tr\u00e1fico que se han borrado, papeleras rotas o jardines descuidados\u201d.<\/p>\n<p>Para Elena esto es un problema real y los ciudadanos muchas veces no saben c\u00f3mo comunicar estas inquietudes al Ayuntamiento. Un problema que tiene soluci\u00f3n con la creaci\u00f3n de una aplicaci\u00f3n inform\u00e1tica con la que se podr\u00e1n resolver todas las incidencias y cuestiones que ayuden a potenciar el municipio.<\/p>\n<p>En segundo lugar, presentamos <strong><a href=\"https:\/\/www.capturatuidea.com\/?p=1216\">\u201cNeveras solidarias\u201d<\/a>.<\/strong> Una propuesta elaborada por Omayra Garc\u00eda y que describe la dif\u00edcil situaci\u00f3n por la que pasan muchas personas d\u00eda a d\u00eda. Para la autora, \u201cla situaci\u00f3n econ\u00f3mica actual ha incitado a que muchas personas, sobre todo aquellas sin recursos, no tengan nada que comer.\u00a0 Sin embargo, aquellas que s\u00ed tienen algo que consumir cada d\u00eda, no valoren algo tan sencillo como comer\u201d.<\/p>\n<p>Para Omayra, la soluci\u00f3n pasa por habilitar un espacio para colocar neveras peque\u00f1as en la que todos los ciudadanos, ciudadanas, bares y restaurantes del municipio puedan depositar alimentos y as\u00ed, las personas sin recursos, pueden recoger esos alimentos en las neveras. <strong>Una propuesta que ha conseguido el premio de \u201cAcc\u00e9sit Social\u201d.<\/strong><\/p>\n<p>El <strong>primer premio<\/strong>, otorgado por la Comisi\u00f3n T\u00e9cnica habilitada para este certamen, fue para la idea de Jos\u00e9 Guti\u00e9rrez denominada <a href=\"https:\/\/www.capturatuidea.com\/?p=1131\"><strong>\u201cApp Compra directa al agricultor\u201d<\/strong><\/a>.\u00a0 El autor establece diferencias claras y evidentes en el precio que pone directamente el agricultor del precio que ponen los comercios. Un problema que pasa por crear una aplicaci\u00f3n donde los agricultores permitan que los particulares o propios comercios hagan la compra directa en la finca, pudiendo incluso, de manera individual, elegir sus propias frutas, verduras y hortalizas.<\/p>\n<p>El <strong>segundo premio<\/strong> fue para la idea <strong><a href=\"https:\/\/www.capturatuidea.com\/?p=1196\">\u201cRed de rutas ciclables\u201d<\/a>.<\/strong> Su autor, Francisco Luis Prieto, destaca que la bicicleta es una herramienta divertida, sana, social y que nunca ha pasado de moda. Por esto, propone la creaci\u00f3n de una red de rutas que sean asequibles para personas de cualquier edad o condici\u00f3n f\u00edsica. Los criterios de las rutas estar\u00edan basados en la b\u00fasqueda de la belleza y el disfrute est\u00e9tico de la ciudad, potenciando as\u00ed el inter\u00e9s cultural y natural del entorno lagunero.<\/p>\n<p>Una iniciativa enmarcada en el proyecto Emprende.LaLaguna 2017 y que est\u00e1 financiado por el Excmo. Ayuntamiento de San Crist\u00f3bal de La Laguna y ejecutado por la Fundaci\u00f3n General Universitaria. Por otro lado, se ha recibido la colaboraci\u00f3n de diferentes entidades privadas que han colaborado en los premios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 30 de junio cerr\u00f3 el plazo votaci\u00f3n de las propuestas registradas en la web oficial de la II Edici\u00f3n de \u201cCaptura tu Idea\u201d. Una iniciativa que busca potenciar la creatividad y el esp\u00edritu emprendedor en el entorno lagunero. La entrega de premios se realizar\u00e1 el 19 de julio en el Paraninfo de la Universidad, a partir de las 19 horas. De las 72 ideas registradas, cuatro de ellas han sido las ganadoras de esta \u00a0II Edici\u00f3n. El premio es un dispositivo m\u00f3vil Aquaris X5 Plus.<\/p>\n","protected":false},"author":10,"featured_media":33530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,4],"tags":[193,46],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2017\/07\/pantallapremios1280x720px-300x169.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33218"}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=33218"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33218\/revisions"}],"predecessor-version":[{"id":33531,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/33218\/revisions\/33531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/33530"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=33218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=33218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=33218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}