{"id":32952,"date":"2017-06-27T15:11:14","date_gmt":"2017-06-27T14:11:14","guid":{"rendered":"https:\/\/www.fg.ull.es\/?p=32952\/"},"modified":"2017-12-05T10:15:56","modified_gmt":"2017-12-05T10:15:56","slug":"tres-dias-para-cerrar-el-plazo-de-votacion-de-la-ii-edicion-de-captura-tu-idea","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/noticias\/2017\/06\/27\/tres-dias-para-cerrar-el-plazo-de-votacion-de-la-ii-edicion-de-captura-tu-idea\/","title":{"rendered":"\u00daltimos d\u00edas antes de cerrar el plazo de votaci\u00f3n de la II Edici\u00f3n de \u201cCaptura tu Idea\u201d"},"content":{"rendered":"<h1>\u00daltimos d\u00edas antes de cerrar el plazo de votaci\u00f3n de la II Edici\u00f3n de \u201cCaptura tu Idea\u201d<\/h1>\n<h4>El pr\u00f3ximo 30 de junio da por finalizado el plazo de votaci\u00f3n de las ideas registradas en el concurso lagunero de<a href=\"https:\/\/www.capturatuidea.com\/\"> \u201cCaptura tu idea\u201d<\/a>. \u00a0Una iniciativa creada por y para detectar problemas o inconvenientes que hay en La Laguna y poder ponerle una soluci\u00f3n, con el objetivo principal de fomentar la creatividad y el esp\u00edritu emprendedor. El premio para las cuatro iniciativas ganadoras es un dispositivo m\u00f3vil.<\/h4>\n<p>Un total de 72 ideas se registraron el pasado 16 de junio en <a href=\"https:\/\/premium.easypromosapp.com\/p\/812130?lc=es-es\">la plataforma oficial de \u201cCaptura tu Idea\u201d<\/a> con la premisa de empezar la votaci\u00f3n por parte del p\u00fablico y participantes al concurso. Una votaci\u00f3n que se cierra el 30 de junio y que da lugar a la deliberaci\u00f3n de la comisi\u00f3n t\u00e9cnica, encargada de comunicar las cuatro propuestas ganadoras del certamen.<\/p>\n<p>Neveras solidarias, mejoras de accesibilidad y carreteras, aplicaciones para mejorar la alimentaci\u00f3n o la gesti\u00f3n cultural, alquiler p\u00fablico de bicicletas, papeleras para residuos org\u00e1nicos, control de colonias callejeras de gatos, inclusi\u00f3n en parques infantiles o bibliotecas callejeras son algunas de las ideas plasmadas en la web capturatuidea.com.<\/p>\n<p>Mediante fotos, videos o archivos multimedia, los participantes han descrito situaciones susceptibles de ser mejoradas y que puedan potenciar y mejorar el municipio de San Crist\u00f3bal de La Laguna.<\/p>\n<p>De las 72 ideas en la web, once de ellas ser\u00e1n las m\u00e1s votadas y pasar\u00e1n a la mencionada comisi\u00f3n. La iniciativa m\u00e1s votada tendr\u00e1 el premio del p\u00fablico, otras dos ser\u00e1n escogidas como mejor iniciativas y de entre todas las ideas, la comisi\u00f3n otorgar\u00e1 otro premio a aquella que ofrezca una mayor proyecci\u00f3n social.<\/p>\n<p>Este concurso se enmarca en el programa Emprende.LaLaguna, que se viene desarrollando desde hace m\u00e1s de cuatro a\u00f1os entre la Concejal\u00eda de Econom\u00eda, Empresa y Empleo del Ayuntamiento de La Laguna y la Universidad de La Laguna, a trav\u00e9s de su Fundaci\u00f3n General.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 30 de junio da por finalizado el plazo de votaci\u00f3n de las ideas registradas en el concurso lagunero de \u201cCaptura tu idea\u201d. \u00a0Una iniciativa creada por y para detectar problemas o inconvenientes que hay en La Laguna y poder ponerle una soluci\u00f3n, con el objetivo principal de fomentar la creatividad y el esp\u00edritu emprendedor. El premio para las cuatro iniciativas es un dispositivo m\u00f3vil BQ Aquaris X5 Plus.<\/p>\n","protected":false},"author":10,"featured_media":32466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[193,46],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/noticias\/wp-content\/uploads\/sites\/2\/2017\/05\/banner_Facebook1200x600px-300x157.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/32952"}],"collection":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/comments?post=32952"}],"version-history":[{"count":1,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/32952\/revisions"}],"predecessor-version":[{"id":34796,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/posts\/32952\/revisions\/34796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media\/32466"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/media?parent=32952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/categories?post=32952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/noticias\/wp-json\/wp\/v2\/tags?post=32952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}