{"id":9032,"date":"2011-08-24T13:24:11","date_gmt":"2011-08-24T13:24:11","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=9032"},"modified":"2011-08-24T13:24:11","modified_gmt":"2011-08-24T13:24:11","slug":"hoy-finaliza-el-plazo-para-el-curso-aenor-gestion-de-la-responsabilidad-social-rs10","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2011\/08\/24\/hoy-finaliza-el-plazo-para-el-curso-aenor-gestion-de-la-responsabilidad-social-rs10\/","title":{"rendered":"Hoy finaliza el plazo para el Curso AENOR: &#039;Gesti\u00f3n de la Responsabilidad Social RS10&#039;"},"content":{"rendered":"<p>La Responsabilidad Social se est\u00e1 consolidando como una de las tendencias fundamentales del panorama empresarial actual como forma de dar respuesta al desarrollo sostenible.<\/p>\n<p style='text-align: justify'>Esta <strong>formaci&oacute;n es exclusiva de AENOR<\/strong> y est&aacute; presente por primera vez en su cat&aacute;logo formativo del 2011, por lo que es totalmente nuevo en Espa&ntilde;a. Los alumnos y alumnas que superen el curso ser&aacute;n los primeros en toda Canarias en disponer de una titulaci&oacute;n oficial reconocida por AENOR y v&aacute;lida en todo el pa&iacute;s para el ejercicio de competencias profesionales en esta materia.<\/p>\n<p style='text-align: justify'>Gracias al<strong> acuerdo de colaboraci&oacute;n <\/strong>suscrito entre <strong><a href='http:\/\/www.aenor.es\/aenor\/inicio\/home\/home.asp' target='_blank' rel=\"noopener noreferrer\">AENOR<\/a> <\/strong>y la <strong>FEULL<\/strong> se puede ofrecer en Tenerife y a los precios indicados en la tabla, estando una parte bonificada por la propia FEULL.<\/p>\n<p style='text-align: justify'><strong>Fecha y lugar de celebraci&oacute;n:&nbsp;<\/strong>26 y 27 de Octubre de 2011 en las instalaciones de la FEULL.<\/p>\n<p style='text-align: justify'><strong>Duraci&oacute;n y horario del curso:&nbsp;<\/strong>2 d&iacute;as -14 horas.<\/p>\n<p style='text-align: justify'><strong>N&ordm; de plazas: <\/strong>20, de las cuales se reservan 5 plazas para personas en situaci&oacute;n de desempleo (*), y si &eacute;stas no fueran cubiertas pasar&aacute;n al cupo general. En todo caso las plazas ser&aacute;n ocupadas en estricto orden de matriculaci&oacute;n, configur&aacute;ndose una lista de reserva para aquellos interesados que no obtengan plaza.<\/p>\n<p style='text-align: justify'><strong>Matr&iacute;cula y formas de pago:<\/strong><\/p>\n<p style='text-align: justify'>El coste de matr&iacute;cula bonificada se expresa en la siguiente tabla y su alta bonificaci&oacute;n s&oacute;lo se aplicar&aacute; en esta primera edici&oacute;n:<\/p>\n<table style='text-align: justify' border='1' cellspacing='0' cellpadding='0' width='362'>\n<tbody>\n<tr>\n<td width='226' valign='top'>\n<p style='text-align: left'>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Tipos de matr&iacute;cula<\/p>\n<\/td>\n<td width='137' valign='top'>\n<p>&nbsp; &nbsp; Importe Bonificado<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='226' valign='top'>\n<p style='text-align: center'>&nbsp; &nbsp; &nbsp; &nbsp; Normal<\/p>\n<\/td>\n<td width='137' valign='top'>\n<p align='center'>300<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='226' valign='top'>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Universitarios<\/p>\n<\/td>\n<td width='137' valign='top'>\n<p align='center'>250<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='226' valign='top'>\n<p style='text-align: center'>&nbsp; &nbsp; &nbsp;Desempleado (5 max)*<\/p>\n<\/td>\n<td width='137' valign='top'>\n<p style='text-align: center'>220<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style='text-align: justify'><strong>*<\/strong>Personas en situaci&oacute;n laboral de desempleo, que se encuentren inscritos como demandantes de empleo y est&eacute;n percibiendo o hayan percibido durante el a&ntilde;o 2011 la correspondiente prestaci&oacute;n econ&oacute;mica por desempleo. Imprescindible presentar copia de cartilla de desempleo en vigor&nbsp; y justificante del cobro de la prestaci&oacute;n.<\/p>\n<p style='text-align: justify'>La matr&iacute;cula se podr&aacute; hacer on-line s&oacute;lo en caso de que esta sea matr&iacute;cula sin descuento. En el caso de querer aplicarse el descuento por universitario o desempleado, siempre y cuando se cumplan los requisitos y se aporte la justificaci&oacute;n,&nbsp; &eacute;sta deber&aacute; hacerse en la secretar&iacute;a FEULL.<\/p>\n<p style='text-align: justify'>La matr&iacute;cula ha estado abierta desde el 23 de agosto y hoy finaliza el plazo. &nbsp;<\/p>\n<p style='text-align: justify'>La <strong>forma de pago de la matricula<\/strong> ser&aacute; la siguiente:<\/p>\n<ul style='text-align: justify'>\n<li>Un periodo de pago &uacute;nico<span style='text-decoration: underline'> <\/span>para el total de la matr&iacute;cula.<\/li>\n<li>Un periodo de pago fraccionado.<\/li>\n<\/ul>\n<p style='text-align: justify'>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Pago inicial para reserva de plaza del 30%<\/p>\n<p style='text-align: justify'>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Pago del resto de la matricula antes del 30 de Septiembre<\/p>\n<p style='text-align: justify'>&nbsp;<\/p>\n<p style='text-align: justify'><a href='..\/..\/public\/docs\/327_4r_curso_aenor__gestion_de_la_responsabilidad_social_rs10.pdf' target='_blank' rel=\"noopener noreferrer\">M&aacute;s informaci&oacute;n<\/a><\/p>\n<p style='text-align: justify'><a href='..\/..\/public\/docs\/320_vm_curso_aenor__gestion_de_la_responsabilidad_social_rs10.pdf' target='_blank' rel=\"noopener noreferrer\"> <\/a><\/p>\n<p style='text-align: justify'>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Responsabilidad Social se est\u00e1 consolidando como una de las tendencias fundamentales del panorama empresarial actual como forma de dar respuesta al desarrollo sostenible.<\/p>\n","protected":false},"author":36,"featured_media":9031,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6],"tags":[173],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/321_5i_logo_aenor.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/9032"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=9032"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/9032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/9031"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=9032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=9032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=9032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}