{"id":8773,"date":"2011-04-28T15:14:03","date_gmt":"2011-04-28T15:14:03","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=8773"},"modified":"2011-04-28T15:14:03","modified_gmt":"2011-04-28T15:14:03","slug":"quinientos-alumnos-de-la-universidad-de-la-laguna-se-beneficiaran-de-la-beca-prolingua","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2011\/04\/28\/quinientos-alumnos-de-la-universidad-de-la-laguna-se-beneficiaran-de-la-beca-prolingua\/","title":{"rendered":"Quinientos alumnos de la Universidad de La Laguna se beneficiar\u00e1n de la Beca Prolingua"},"content":{"rendered":"<p>Estas ayudas de la Direcci\u00f3n General de Universidades del Gobierno de Canarias se gestionan a trav\u00e9s de la Fundaci\u00f3n Empresa-Universidad<\/p>\n<p align='justify'>La <a href='http:\/\/www.gobiernodecanarias.org\/educacion\/'>Direcci&oacute;n General de Universidades e Investigaci&oacute;n del Gobierno de Canarias<\/a> financia desde 2005 las Becas Prolingua, con el objetivo de facilitar que el alumnado de las instituciones p&uacute;blicas de educaci&oacute;n superior adquieran durante sus a&ntilde;os de formaci&oacute;n unas competencias idiom&aacute;ticas adecuadas para desenvolverse en contextos acad&eacute;micos y profesionales internacionales. Estas ayudas est&aacute;n gestionadas en la Universidad a trav&eacute;s de la Fundaci&oacute;n Empresa Universidad (FEULL), y est&aacute; previsto que para el curso que viene beneficien a quinientos estudiantes del centro tinerfe&ntilde;o.<\/p>\n<p align='justify'>El Rectorado de la ULL ha acogido hoy, jueves 28 de abril, la presentaci&oacute;n de un balance de los resultados de la convocatoria del presente curso 2010-2011, as&iacute; como un avance de las previsiones para el pr&oacute;ximo curso acad&eacute;mico. En &eacute;l estuvieron presentes el rector de la instituci&oacute;n acad&eacute;mica, Eduardo Dom&eacute;nech; el director general de Universidades e Investigaci&oacute;n del Gobierno de Canarias, Juan Jos&eacute; Mart&iacute;nez; el director gerente de la FEULL, Sergio Alonso; y la directora del Departamento de Fomento del Empleo de la misma fundaci&oacute;n, In&eacute;s Ruiz.<\/p>\n<p align='justify'>Las Becas Prolingua sufragan parcialmente los gastos de matr&iacute;cula en cursos de idiomas de cincuenta horas. El <a href='..\/..\/es\/proyecto\/servicio_de_idiomas\/5\/'>Servicio de Idiomas<\/a> que gestiona la FEULL los oferta a un precio de 225 euros, y dado que el importe de la ayuda es de 175, sus beneficiarios solamente tendr&iacute;an que abonar 50 euros. El programa tambi&eacute;n incluye diez ayudas para acciones formativas que se desarrollen durante tres meses en empresas for&aacute;neas de sectores econ&oacute;micos considerados de inter&eacute;s para Canarias.<\/p>\n<p align='justify'>El rector de la ULL aprovech&oacute; su intervenci&oacute;n para agradecer al ejecutivo regional, y especialmente a su Direcci&oacute;n General de Universidades e Investigaci&oacute;n, todo el esfuerzo presupuestario que est&aacute;n realizando para mantener unas ayudas que consider&oacute; muy necesarias para promover la movilidad de los alumnos y la proyecci&oacute;n internacional de la instituci&oacute;n. Adicionalmente, valor&oacute; la capacidad demostrada por la FEULL para gestionar estas becas, y de su Servicio de Idiomas para impartir los cursos. Para Dom&eacute;nech, contar con una mejor formaci&oacute;n idiom&aacute;tica supone un factor estrat&eacute;gico para poder ?responder a las expectativas que plantean retos como la Estrategia Universidad 2015 y el Campus de Excelencia?.<\/p>\n<p align='justify'>El gerente de la FEULL destac&oacute; la gran aceptaci&oacute;n que han tenido estas becas, revelando que se recibieron m&aacute;s de mil solicitudes para las 500 ayudas publicadas el curso 2010-2011, tendencia que prev&eacute; contin&uacute;e en la siguiente convocatoria. En opini&oacute;n de Sergio Alonso, es una demostraci&oacute;n del inter&eacute;s que existe entre los universitarios por mejorar sus competencias idiom&aacute;ticas, puesto que tras la adaptaci&oacute;n al <a href='http:\/\/www.eees.es\/'>Espacio Europeo de Educaci&oacute;n Superior<\/a>, para acceder a los estudios de posgrado se exigir&aacute; a los alumnos poseer al grado B1 de ingl&eacute;s.<\/p>\n<p align='justify'>Alonso explic&oacute; que ha mantenido reuniones con decanos y directores de escuela para poder disponer de aulas en los diferentes centros, con el fin de que el Servicio de Idiomas de la FEULL pueda impartir estos cursos de idiomas de manera descentralizada, en espacios cercanos al alumnado y en horarios compatibles con sus estudios. Ya se ha desarrollado una experiencia piloto de clases complementarias de alem&aacute;n para alumnos del Grado en Turismo, y pr&oacute;ximamente habr&aacute; aulas en los campus Central, de Anchieta y de Guajara. Una segunda etapa de este plan comenzar&aacute; en mayo, dirigida a mejorar las habilidades en idiomas del profesorado, para facilitar que puedan impartir clases en otro idioma o defender una ponencia en el extranjero.<\/p>\n<p align='justify'>Por su parte, el director general de Universidades e Investigaci&oacute;n recalc&oacute; que las Becas Prolingua forman parte de una serie de iniciativas que, desde el ejecutivo regional, se est&aacute;n promoviendo para facilitar la mejora de las competencias ling&uuml;&iacute;sticas de los estudiantes. Se&ntilde;al&oacute; como ejemplo las ayudas complementarias que se da a los Erasmus canarios, gracias a las cuales se ha podido pasar de 500 a casi un millar de alumnos que participan en este programa de intercambio europeo.<\/p>\n<p align='justify'>Para Mart&iacute;nez, que la poblaci&oacute;n posea conocimientos de otros idiomas es imprescindible para el futuro: ?La internacionalizaci&oacute;n no es s&oacute;lo convertir Canarias en una plataforma log&iacute;stica o apostar por el turismo. Tambi&eacute;n lo es contar con profesionales capaces de proveer de servicios cualificados al norte de &Aacute;frica?, para lo cual el factor idiom&aacute;tico es clave.<\/p>\n<p align='justify'><a href='http:\/\/www.laopinion.es\/sociedad\/2011\/04\/28\/alumnos-beneficiaran-beca-prolingua\/342521.html'>La Opini&oacute;n de Tenerife<\/a><\/p>\n<p align='justify'><a href='http:\/\/www.eldigitaldecanarias.net\/noticia48476.php'>El Digital de Canarias<\/a><\/p>\n<p align='justify'>(Nota cedida por la ULL)<\/p>\n<div style=\"max-width: 100%;max-height:100%\"><img src='http:\/\/www.fg.ull.es\/wp-content\/uploads\/2015\/04\/219_sv_110428_tfe_rectorado_6.jpg'><\/div>\n<div style=\"max-width: 100%;max-height:100%\"><img src='http:\/\/www.fg.ull.es\/wp-content\/uploads\/2015\/04\/220_j9_110428_tfe_rectorado_7.jpg'><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estas ayudas de la Direcci\u00f3n General de Universidades del Gobierno de Canarias se gestionan a trav\u00e9s de la Fundaci\u00f3n Empresa-Universidad<\/p>\n","protected":false},"author":36,"featured_media":8770,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[173],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/218_wd_110428_tfe_rectorado_1-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/8773"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=8773"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/8773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/8770"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=8773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=8773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=8773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}