{"id":8414,"date":"2011-01-26T11:15:48","date_gmt":"2011-01-26T11:15:48","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=8414"},"modified":"2011-01-26T11:15:48","modified_gmt":"2011-01-26T11:15:48","slug":"se-abre-el-plazo-para-participar-en-el-ii-foro-innovaccion","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2011\/01\/26\/se-abre-el-plazo-para-participar-en-el-ii-foro-innovaccion\/","title":{"rendered":"Se abre el plazo  para participar en el II Foro InnovAcci\u00f3n"},"content":{"rendered":"<p>\u00bfTienes un invento o proyecto tecnol\u00f3gico altamente innovador y quieres participar  como expositor en el mayor Foro de Innovaci\u00f3n de Tenerife?<\/p>\n<p align='justify'>Desde el II Foro InnovAccion se invita a participar a todas las personas que&nbsp;est&eacute;n trabajando en&nbsp;proyectos de emprendedur&iacute;a e innovaci&oacute;n.<\/p>\n<p align='justify'>El II Foro InnovAcci&oacute;n, que tendr&aacute; lugar en el recinto Ferial de Santa Cruz de Tenerife los d&iacute;as 24 y 25 de marzo de 2011, tiene el objetivo de apoyar a todas las personas o empresas que son conscientes de que s&oacute;lo emprendiendo e innovando se podr&aacute; contribuir a la renovaci&oacute;n del modelo socio-econ&oacute;mico actual y, as&iacute;, asentar los pilares de la nueva econom&iacute;a del conocimiento hacia la que se orienta la sociedad dentro de un contexto de competitividad global.<\/p>\n<p align='justify'>En el marco de este Foro se combinar&aacute;n actividades formativas en mesas y talleres de trabajo, se otorgar&aacute;n premios a los mejores proyectos presentados en el foro de inversi&oacute;n TFInvierte, habr&aacute; una amplia zona de exposici&oacute;n para difundir proyectos innovadores de referencia, as&iacute; como de clusters en creaci&oacute;n y fase de consolidaci&oacute;n en las Islas Canarias; y, tambi&eacute;n, existir&aacute; un espacio donde empresas e inventores locales podr&aacute;n dar a conocer sus &uacute;ltimos trabajos.<\/p>\n<p align='justify'>&nbsp;La vocaci&oacute;n de impulsar la emprendedur&iacute;a y la creatividad por parte del Cabildo de Tenerife, a trav&eacute;s del programa <a href='http:\/\/www.tfinnova.es\/'>TF Innova<\/a>, queda acreditada con el &eacute;xito de la primera edici&oacute;n del Foro, celebrada en el a&ntilde;o 2010, que registr&oacute; un alto nivel de asistencia y participaci&oacute;n activa, tanto en las mesas de debate como en los talleres de trabajo, de empresas y de profesionales destacados en el &aacute;mbito de la I D i.<\/p>\n<p align='justify'>Confirma tu inter&eacute;s mandando un mail a <a href='mailto:documentacion@tfinnova.es'>documentacion@tfinnova.es<\/a>&nbsp;y recibir&aacute;s la informaci&oacute;n que se necesita de tu proyecto para que puedas enviar tu solicitud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTienes un invento o proyecto tecnol\u00f3gico altamente innovador y quieres participar  como expositor en el mayor Foro de Innovaci\u00f3n de Tenerife?<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[173,533,614,672,821],"featured_image_thumbnail_url":null,"_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/8414"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=8414"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/8414\/revisions"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=8414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=8414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=8414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}