{"id":27050,"date":"2016-06-30T10:34:18","date_gmt":"2016-06-30T09:34:18","guid":{"rendered":"http:\/\/www.fg.ull.es\/es\/?p=27050"},"modified":"2016-06-30T10:34:18","modified_gmt":"2016-06-30T09:34:18","slug":"el-servicio-de-biblioteca-de-la-ull-presenta-en-el-festival-starmus-un-video-sobre-obras-de-astronomia-en-sus-fondos-especiales","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2016\/06\/30\/el-servicio-de-biblioteca-de-la-ull-presenta-en-el-festival-starmus-un-video-sobre-obras-de-astronomia-en-sus-fondos-especiales\/","title":{"rendered":"El Servicio de Biblioteca de la ULL presenta en el Festival Starmus un video sobre obras de astronom\u00eda en sus fondos especiales"},"content":{"rendered":"<h1 class=\"entry-title\">El Servicio de Biblioteca de la ULL presenta en el Festival Starmus un video sobre obras de astronom\u00eda en sus fondos especiales<\/h1>\n<h4>El festival STARMUS, que se celebra entre el 27 de junio y el 1 de julio, ha contado entre sus actividades con la proyecci\u00f3n en primicia del v\u00eddeo <em>Estrellas en la Biblioteca. Astronom\u00eda en las colecciones especiales de la Biblioteca Universitaria,<\/em>realizado por el Servicio de Biblioteca de la Universidad de La Laguna.<\/h4>\n<p>El v\u00eddeo recopila una\u00a0muestran de im\u00e1genes de obras de los siglos XV hasta la actualidad relacionadas con la astronom\u00eda y que forman parte del Fondo Antiguo y del Fondo de Canarias de la Biblioteca Universitaria.<br \/>\nEntre las obras seleccionadas destacan por su rareza el incunable\u00a0<em>De propietatibus rerum\u00a0<\/em>(1494) y varias ediciones del siglo XVI de obras de Beda el Venerable, Arist\u00f3teles y Santo Tom\u00e1s de Aquino que tratan sobre fen\u00f3menos astron\u00f3micos. Tambi\u00e9n varias joyas del siglo XVII como el\u00a0<em>Uso de los antoios<\/em>\u00a0\u00a0de Daza y Vald\u00e9s, de<em>\u00a0<\/em>especial relevancia para la historia de los telescopios, y del siglo XVIII los grabados de la edici\u00f3n pr\u00edncipe de la\u00a0<em>Encyclop\u00e9die<\/em>\u00a0de Diderot y D\u2019Alembert.<br \/>\nRelacionadas con Canarias sobresalen la obra del historiador Jos\u00e9 Viera y Clavijo,\u00a0<em>Noticias del cielo \u00f3 astronomia para ni\u00f1os\u00a0<\/em>(1811), la del astr\u00f3nomo Charles Piazzi Smyth,\u00a0<em>Teneriffe, an astronomer\u2019s experiment<\/em>\u00a0(1858), en la que se describe la primera observaci\u00f3n astron\u00f3mica cient\u00edfica realizada desde el Teide,<em>\u00a0<\/em>y la de Jean Mascart,\u00a0<em>Impressions et observations dans un voyage \u00e0 T\u00e9n\u00e9rife<\/em>\u00a0publicada en 1908.<br \/>\nEl v\u00eddeo\u00a0<em>\u201cEstrellas en la Biblioteca, Astronom\u00eda en las colecciones especiales de la Biblioteca Universitaria\u201d <\/em>est\u00e1 disponible <a href=\"http:\/\/www.bbtk.ull.es\/view\/institucional\/bbtk\/Inicio\/es\" target=\"_blank\" rel=\"noopener noreferrer\">en la web de la Biblioteca Universitaria.<\/a><br \/>\n&nbsp;<br \/>\nExtra\u00eddo del\u00a0<a href=\"http:\/\/ddigital.webs.ull.es\/el-servicio-de-biblioteca-de-la-ull-presenta-en-el-festival-starmus-un-video-sobre-obras-de-astronomia-en-sus-fondos-especiales\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Diario Digital<\/em> <\/a>de la ULL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El festival STARMUS, que se celebra entre el 27 de junio y el 1 de julio, ha contado entre sus actividades con la proyecci\u00f3n en primicia del v\u00eddeo Estrellas en la Biblioteca. Astronom\u00eda en las colecciones especiales de la Biblioteca Universitaria,realizado por el Servicio de Biblioteca de la Universidad de La Laguna.<\/p>\n","protected":false},"author":37,"featured_media":27051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[917,1285,1313],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2016\/06\/11-300x167.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/27050"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=27050"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/27050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/27051"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=27050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=27050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=27050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}