{"id":24839,"date":"2016-03-31T13:37:37","date_gmt":"2016-03-31T12:37:37","guid":{"rendered":"http:\/\/www.fg.ull.es\/es\/?p=24839"},"modified":"2016-03-31T13:37:37","modified_gmt":"2016-03-31T12:37:37","slug":"la-seccion-de-ingenieria-nautica-de-la-ull-recibe-la-visita-del-ceo-andres-orozco","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2016\/03\/31\/la-seccion-de-ingenieria-nautica-de-la-ull-recibe-la-visita-del-ceo-andres-orozco\/","title":{"rendered":"La Secci\u00f3n de Ingenier\u00eda Na\u00fatica de la ULL recibe la visita del CEO Andr\u00e9s Orozco"},"content":{"rendered":"<h1><strong>La Secci\u00f3n de Ingenier\u00eda Na\u00fatica de la ULL recibe la visita del CEO Andr\u00e9s Orozco<\/strong><\/h1>\n<h4>Un grupo de estudiantes de este centro de ense\u00f1anza realiz\u00f3 el pasado 28 de marzo esta ruta cient\u00edfica, como parte del \u201cProyecto Programa de Apoyo para la Generaci\u00f3n de nuevos cient\u00edficos\/as y Tecn\u00f3logos\/as de la Isla de Tenerife\u201d<\/h4>\n<p>Ayer el 28 de marzo, veinticuatro alumnos y alumnas del instituto de Arafo, visitaron la Escuela T\u00e9cnica Superior de N\u00e1utica, M\u00e1quinas y Radioelectr\u00f3nica Naval, donde pudieron acercarse a la ingenier\u00eda mar\u00edtima.<br \/>\nLa profesora de Construcciones Navales, M\u00aa del Cristo Adri\u00e1n de Ganzo, mostr\u00f3 a los estudiantes las instalaciones y el trabajo que se realiza en el centro, explic\u00e1ndoles el desarrollo y procedimientos de trabajo en motores de combusti\u00f3n interna marinos. Posteriormente, el profesor de la ULL especializado Ingenier\u00eda de los Procesos de Fabricaci\u00f3n, Federico Padr\u00f3n Mart\u00edn,\u00a0 y un grupo de sus alumnos de 4\u00ba curso, ejercieron de gu\u00edas para mostrar los diferentes mecanizados con herramientas manuales. La visita termin\u00f3 con los chicos y chicas realizando\u00a0 varios ejercicios pr\u00e1cticos de supervivencia en el mar.<br \/>\nEl Grupo de Investigaci\u00f3n Contaminaci\u00f3n y Seguridad Marina (CONSEMAR) conformado por Juan Imeldo G\u00f3mez, Alexis Dionis Meli\u00e1n, Agust\u00edn Gonz\u00e1lez Almeida, Federico Padr\u00f3n Mart\u00edn, M\u00aa del Cristo Adri\u00e1n de Ganzo y Amanda Pe\u00f1a Navarro, alumna de Doctorado, contribuyeron al desarrollo de esta actividad educativa.<br \/>\nLa visita forma parte del \u201cProyecto Programa de Apoyo para la Generaci\u00f3n de nuevos cient\u00edficos\/as y Tecn\u00f3logos\/as de la Isla de Tenerife\u201d , impulsado por la Fundaci\u00f3n CajaCanarias, en el marco de la convocatoria 2015 de Proyectos Educativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de estudiantes de este centro de ense\u00f1anza realiz\u00f3 el pasado 28 de marzo esta ruta cient\u00edfica, como parte del \u201cProyecto Programa de Apoyo para la Generaci\u00f3n de nuevos cient\u00edficos\/as y Tecn\u00f3logos\/as de la Isla de Tenerife\u201d<\/p>\n","protected":false},"author":37,"featured_media":24840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[336,1189,1396],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2016\/03\/20160328_131642-300x225.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/24839"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=24839"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/24839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/24840"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=24839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=24839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=24839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}