{"id":15801,"date":"2015-01-30T11:36:09","date_gmt":"2015-01-30T11:36:09","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=15801"},"modified":"2015-01-30T11:36:09","modified_gmt":"2015-01-30T11:36:09","slug":"abierta-la-convocatoria-para-la-seleccion-del-proyecto-que-representara-a-la-ull-en-los-vii-premios-uniproyecta","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2015\/01\/30\/abierta-la-convocatoria-para-la-seleccion-del-proyecto-que-representara-a-la-ull-en-los-vii-premios-uniproyecta\/","title":{"rendered":"Abierta la convocatoria para la selecci\u00f3n del proyecto que representar\u00e1 a la ULL en los VII Premios UNI&#062;PROYECTA"},"content":{"rendered":"<p>Hasta el 27 de febrero permanecer&aacute; abierto el plazo para que los estudiantes de la ULL puedan participar en la selecci&oacute;n del mejor proyecto emprendedor de la universidad.<\/p>\n<p><\/p>\n<p>El pasado martes, 27 de enero, se abri&oacute; el plazo de presentaci&oacute;n para que los estudiantes de la Universidad de La Laguna puedan participar en la selecci&oacute;n del proyecto emprendedor que representar&aacute; a la universidad en la VII edici&oacute;n de los premios UNI&gt;PROYECTA, a nivel nacional. Estos premios est&aacute;n convocados por el Portal Universia y la Red Universitaria de Asuntos Estudiantiles (RUNAE) y su objetivo es reconocer los proyectos emprendedores universitarios de excelencia, con objeto de fomentar el esp&iacute;ritu emprendedor entre la comunidad universitaria y estimular la iniciativa empresarial.<\/p>\n<p>El Vicerrectorado de Alumnado de la ULL ser&aacute; el encargado de organizar la selecci&oacute;n el proyecto que representar&aacute; a la universidad y del proyecto reserva. Los estudiantes o titulados universitarios, que hayan obtenido el t&iacute;tulo en los dos a&ntilde;os inmediatamente anteriores al presente curso acad&eacute;mico, interesados en participar deber&aacute;n entregar sus proyectos y toda la documentaci&oacute;n que se establece en las bases, hasta el 27 de febrero en el Registro General de la ULL y dirigido al Vicerrectorado de Alumnado. &nbsp;<\/p>\n<p>Posteriormente, del 28 de febrero al 3 de marzo, se reunir&aacute; un jurado compuesto por la Vicerrectora de Alumnado de la Universidad, el Director de la C&aacute;tedra Fundaci&oacute;n DISA de J&oacute;venes Emprendedores de la ULL y el Director Gerente de la Fundaci&oacute;n General de la Universidad, que seleccionar&aacute; el proyecto que representar&aacute; a la ULL a nivel nacional y competir&aacute; con el resto de proyectos de otras universidades espa&ntilde;olas.<\/p>\n<p>UNIPROYECTA est&aacute; dirigido a proyectos empresariales en los que participen de forma individual o en grupo, estudiantes y titulados universitarios. As&iacute;, en la edici&oacute;n nacional se entregar&aacute;n dos premios:<\/p>\n<ul>\n<li><strong>Premio Uniproyecta Portal Universia<\/strong>, al mejor proyecto emprendedor universitario, dotado de 10.000 euros y diploma acreditativo otorgado por el Portal Universia. <\/li>\n<li><strong>Premio Uniproyecta Fundaci&oacute;n Universia<\/strong>, al mejor proyecto orientado a la atenci&oacute;n a las personas con discapacidad, dotado con 5.000 euros y diploma acreditativo otorgado por la Fundaci&oacute;n Universia.<\/li>\n<\/ul>\n<p>Para m&aacute;s informaci&oacute;n ver las <a href='http:\/\/www.ull.es\/Private\/folder\/institucional\/ull\/wull\/destacados\/empleabilidad\/bases_uniproyecta.pdf'>bases del VII Premio UNI&gt;PROYECTA<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta el 27 de febrero permanecer&aacute; abierto el plazo para que los estudiantes de la ULL puedan participar en la selecci&oacute;n del mejor proyecto emprendedor de la universidad.<\/p>\n","protected":false},"author":36,"featured_media":15800,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[173,533,541,1353,1424],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/2669_pe_universia.png","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/15801"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=15801"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/15801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/15800"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=15801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=15801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=15801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}