{"id":15795,"date":"2015-01-30T09:49:37","date_gmt":"2015-01-30T09:49:37","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=15795"},"modified":"2015-01-30T09:49:37","modified_gmt":"2015-01-30T09:49:37","slug":"la-ull-recibe-hoy-a-los-82-estudiantes-erasmus-que-cursaran-el-segundo-cuatrimestre","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2015\/01\/30\/la-ull-recibe-hoy-a-los-82-estudiantes-erasmus-que-cursaran-el-segundo-cuatrimestre\/","title":{"rendered":"La ULL recibe hoy a los 82 estudiantes Erasmus que cursar\u00e1n el segundo cuatrimestre"},"content":{"rendered":"<p>La jornada de bienvenida comenzar&aacute; a las 11 horas en la Sala de Audiovisuales de la Secci&oacute;n de Filolog&iacute;a de la Facultad de Humanidades, donde se presentar&aacute; la oferta de deportes, biblioteca, SIO y de los cursos del Servicio de Idiomas. A las 12:30 tendr&aacute; lugar el acto de bienvenida.<\/p>\n<p><\/p>\n<p>La Universidad de La Laguna celebra hoy, viernes 30 de enero, a las  12:30 horas en la Sala de Audiovisuales de la Secci&oacute;n de Filolog&iacute;a de  la Facultad de Humanidades (Campus de Guajara) la jornada de  bienvenida a los alumnos extranjeros del programa de intercambio Erasmus  que permanecer&aacute;n en el centro durante el segundo cuatrimestre del curso  2014-15.<\/p>\n<p>El acto estar&aacute; presidido por el rector de la instituci&oacute;n acad&eacute;mica,  Eduardo Dom&eacute;nech, y contar&aacute; con la presencia del vicerrector de  Internacionalizaci&oacute;n y Excelencia, Rodrigo Trujillo, y el director de  secretariado de Movilidad, Alejandro F. L&oacute;pez de Vergara.<\/p>\n<p> Previamente, a las 11 horas en el mismo lugar, diferentes servicios de  la instituci&oacute;n presentar&aacute;n su oferta al alumnado reci&eacute;n llegado:  concretamente, los de Deportes, Biblioteca, SIO e Idiomas. El Servicio de Idiomas de la Universidad de La Laguna dar&aacute; una charla informativa sobre su oferta de cursos de espa&ntilde;ol para extranjeros, as&iacute; como del resto de su oferta formativa.<\/p>\n<p> En este segundo cuatrimestre llegar&aacute;n 82 estudiantes de pr&aacute;cticamente  todos pa&iacute;ses de la Uni&oacute;n Europea, aunque los que aportan m&aacute;s estudiantes  son Italia (32) y Alemania (16), seguidos a gran distancia por la  Rep&uacute;blica Checa (8), Francia (6) y Dinamarca (4). Por sexos, 59 de estos  Erasmus son mujeres y los 22 restantes, hombres. <\/p>\n<p> El pasado septiembre se celebr&oacute; la recepci&oacute;n a los 245 Erasmus que  permanecieron en la ULL durante el primer cuatrimestre o todo el curso  completo, por lo que la cifra total de alumnos recibidos este a&ntilde;o  acad&eacute;mico ha ascendido a 327.<\/p>\n<p>*Nota de prensa y fotograf&iacute;a cedidas por el gabinete de comunicaci&oacute;n de la ULL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jornada de bienvenida comenzar&aacute; a las 11 horas en la Sala de Audiovisuales de la Secci&oacute;n de Filolog&iacute;a de la Facultad de Humanidades, donde se presentar&aacute; la oferta de deportes, biblioteca, SIO y de los cursos del Servicio de Idiomas. A las 12:30 tendr&aacute; lugar el acto de bienvenida.<\/p>\n","protected":false},"author":36,"featured_media":15794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[173,574,1353,1424],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/2667_ce_bienven_erasmus_sept14__003-300x205.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/15795"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=15795"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/15795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/15794"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=15795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=15795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=15795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}