{"id":14503,"date":"2014-07-25T12:39:43","date_gmt":"2014-07-25T12:39:43","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=14503"},"modified":"2014-07-25T12:39:43","modified_gmt":"2014-07-25T12:39:43","slug":"maribel-sanchez-bonilla-con-intervenciones-como-la-de-la-plaza-del-adelantado-los-estudiantes-aprenden-a-ser-respetuosos-con-el-bien-patrimonial-y-a-razonar-antes-de-actuar-y-eso-es-lo-mas-importa","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2014\/07\/25\/maribel-sanchez-bonilla-con-intervenciones-como-la-de-la-plaza-del-adelantado-los-estudiantes-aprenden-a-ser-respetuosos-con-el-bien-patrimonial-y-a-razonar-antes-de-actuar-y-eso-es-lo-mas-importa\/","title":{"rendered":"Maribel S\u00e1nchez Bonilla: &#039;Con intervenciones como la de la Plaza del Adelantado los estudiantes aprenden a ser respetuosos con el bien patrimonial y a razonar antes de actuar, y eso es lo m\u00e1s importante&#039;"},"content":{"rendered":"<p>La catedr&aacute;tica de Escultura de la ULL, responsable del proyecto de restauraci&oacute;n de Fuente de la conocida plaza lagunera, contesta a una serie de cuestiones sobre su labor investigadora y el valor de este tipo de trabajos para la sociedad y para los estudiantes que colaboran en ellos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><\/p>\n<p style='text-align: left'>&iquest;<strong>En qu&eacute; consiste su actividad investigadora?<\/strong><\/p>\n<p>La actividad investigadora del G.I. Arte y Entorno de la ULL abarca la creaci&oacute;n tridimensional tanto en sus manifestaciones hist&oacute;ricas como en la generaci&oacute;n de nuevas propuestas. Partiendo del an&aacute;lisis de las especificidades de nuestro entorno natural y cultural, se concretan diversas l&iacute;neas de trabajo, que abarcan desde creaci&oacute;n de composiciones escult&oacute;ricas para el espacio urbano, o propuestas creativas con materiales reciclados, hasta actuaciones en conservaci&oacute;n y restauraci&oacute;n de elementos patrimoniales representativos de nuestro pasado hist&oacute;rico o el dise&ntilde;o de elementos adecuados para su puesta en valor y difusi&oacute;n de los valores culturales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&iquest;Cu&aacute;l es su aplicaci&oacute;n directa a la sociedad? &iquest;Qu&eacute; trayectoria tienen los trabajos de restauraci&oacute;n que usted ha dirigido en Tenerife?<\/strong><\/p>\n<p>Realmente, todas las l&iacute;neas de trabajo del grupo derivan en resultados de inter&eacute;s cultural y social. Por ejemplo, se realiz&oacute; el Monumento-Fuente Homenaje al Viticultor Canario, ubicado en la zona de la Alh&oacute;ndiga de Tacoronte, que adem&aacute;s de su propio valor est&eacute;tico consta de un valor derivado de la tem&aacute;tica de los bajorrelieves de piedra bas&aacute;ltica, en los que se representan los aspectos m&aacute;s significativos de la identidad y devenir hist&oacute;rico de la ciudad, quedando abierta la posibilidad de usar el monumento como elemento de inter&eacute;s did&aacute;ctico.<\/p>\n<p>Tambi&eacute;n realizamos la restauraci&oacute;n de la Fuente de M&aacute;rmol de la Alameda del Duque de Santa Elena de Santa Cruz de Tenerife. Dicha fuente, de alto inter&eacute;s hist&oacute;rico, hab&iacute;a sido objeto de un acto vand&aacute;lico que la hab&iacute;a dejado destrozada y fuera de uso; un laborioso proceso de reconstrucci&oacute;n mediante injertos de m&aacute;rmol permiti&oacute; su recuperaci&oacute;n y permanencia en el espacio p&uacute;blico. Igualmente se acometi&oacute; la restauraci&oacute;n de la Pila de la Plaza de La Candelaria de Santa Cruz de Tenerife. Esta pila, realizada en canter&iacute;a de Arucas hace m&aacute;s de tres siglos, tiene un alto valor significativo para la ciudad y para el entorno concreto en que se ubica. Fue necesario reconstruir m&uacute;ltiples detalles ornamentales, debiendo destacar la reposici&oacute;n, mediante injerto del mismo tipo de piedra, de un amplio fragmento de la taza, que hace aproximadamente veinte a&ntilde;os se hab&iacute;a reconstruido con poli&eacute;ster, encontr&aacute;ndose bastante deteriorado. Se procedi&oacute; tambi&eacute;n a la limpieza y tratamiento superficial de la fuente de m&aacute;rmol en cuyo interior se ubica actualmente la pila. La intervenci&oacute;n ha permitido mantener la Pila con plena capacidad funcional.<\/p>\n<p>Y en la ciudad de La Laguna hemos intervenido en varias ocasiones en la restauraci&oacute;n y mantenimiento de la fuente de m&aacute;rmol de la Plaza del Adelantado de La Laguna. La primera ocasi&oacute;n, hace doce a&ntilde;os, permiti&oacute; recuperar esta fuente ornamental, que se encontraba en avanzado estado de deterioro: inutilizada para la contenci&oacute;n y vertido de agua y con importantes alteraciones superficiales. Se han llevado a cabo posteriormente dos actuaciones de mantenimiento, estando prevista una pr&oacute;xima a realizar en octubre de 2014.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Y en el plano estrictamente acad&eacute;mico, &iquest;destacar&iacute;a alg&uacute;n trabajo de investigaci&oacute;n?<\/strong><\/p>\n<p>Pues estamos trabajando en una l&iacute;nea &nbsp;dedicada al an&aacute;lisis de las piedras volc&aacute;nicas, su presencia en el patrimonio y la necesidad de recuperaci&oacute;n de canteras locales, con el objetivo de generar conocimientos necesarios para la restauraci&oacute;n de elementos patrimoniales, que ya ha dado lugar a varias ponencias en congresos y art&iacute;culos de revista. Ya contamos con un grupo de investigadores multidisciplinar de gran nivel y estamos preparando la solicitud de financiaci&oacute;n que permita completar el desarrollo experimental. Tambi&eacute;n hay otra l&iacute;nea abierta relativa a la reutilizaci&oacute;n y contribuci&oacute;n a la sostenibilidad medioambiental con la valoraci&oacute;n y posibles aplicaciones en escultura, pintura, dibujo, etc., de sedimentos minerales ?lodos- de naturaleza bas&aacute;ltica, proyecto que se ha llevado a cabo sin financiaci&oacute;n externa. A partir del trabajo experimental realizado se podr&iacute;a considerar como oportunidad y material viable en diversas t&eacute;cnicas art&iacute;sticas\/artesanales, un tipo de sedimentos que hasta ahora han sido considerados productos de desecho.<\/p>\n<p>Y otro proyecto muy ilusionante es el de las posibles aplicaciones de sedimentos calc&aacute;reos depositados por el agua de las galer&iacute;as. Se trata de encontrar utilidad y aplicaci&oacute;n a unos materiales que hoy son, en Tenerife, un problema medioambiental no resuelto, los resultados iniciales son muy alentadores. Se ha solicitado financiaci&oacute;n en convocatoria nacional, con el objetivo de indagar\/valorar las posibilidades de aplicaci&oacute;n tanto en creaciones pl&aacute;sticas como en la generaci&oacute;n de industrias artesanales. Veremos c&oacute;mo va a avanzando, pero tenemos muy buenas sensaciones con este proyecto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&iquest;Puede profundizar un poco en lo relativo a la intervenci&oacute;n de la fuente de la Plaza de El Adelantado?<\/strong><\/p>\n<p>Han sido cuatro las intervenciones que nuestro grupo ha realizado hasta ahora en la Fuente de las Plaza del Adelantado, entre ellas ha habido elementos t&eacute;cnicos y objetivos similares pero tambi&eacute;n diferencias apreciables.<\/p>\n<p>En la primera ocasi&oacute;n, hace doce a&ntilde;os, hubo que intervenir con procesos abrasivos mec&aacute;nicos (radiales, lijadoras orbitales, fresadoras, etc.) para estabilizar las superficies da&ntilde;adas, as&iacute; como reponer los rejuntes de los diversos m&oacute;dulos que componen la fuente.&nbsp; Tambi&eacute;n fue bastante significativo el trabajo de reposici&oacute;n de fragmentos rotos o desaparecidos mediante injertos realizados con m&aacute;rmol, que se tallaban in situ usando minidiscos diamantados y fresadoras de aire comprimido. Finalmente se puli&oacute; manualmente toda la superficie marm&oacute;rea con lijas de agua de granos sucesivos y con sal de acedera, protegi&eacute;ndola con cera de abeja. En cuanto a la verja, se eliminaron costras de pintura y &oacute;xidos, se modelaron-moldearon-fundieron los elementos que faltaban, y se rellenaron con masilla epoxi las peque&ntilde;as lagunas que hab&iacute;a producido el &oacute;xido en las pletinas met&aacute;lica; una vez completas las formas se aplic&oacute; un tratamiento de prevenci&oacute;n de la oxidaci&oacute;n y se dieron dos manos pintura protectora de acabado de aspecto forja.<\/p>\n<p>En la segunda intervenci&oacute;n, realizada diez a&ntilde;os despu&eacute;s de la primera, se manten&iacute;an en relativo buen estado los injertos y rejuntes, pero se presentaban una gran acumulaci&oacute;n de costras calc&aacute;reas y suciedad, generalizada en toda la superficie marm&oacute;rea, que llegaba a tener un grueso de varios mil&iacute;metros en los interiores de los vasos. Utilizamos rasquetas mec&aacute;nicas y manuales y cepillos circulares de pl&aacute;stico duro, accionados mediante taladros de baja velocidad exentos de percusi&oacute;n. Una vez eliminadas las costras, se procedi&oacute; a lustrar manualmente la superficie marm&oacute;rea mediante lijas y raspines diamantados, finalizando con un tratamiento superficial mediante emulsi&oacute;n jabonosa. Dado el l&iacute;mite presupuestario, quedaron pendientes la limpieza a nivel de detalles, la eliminaci&oacute;n de parte de las costras internas de los vasos superiores y el tratamiento de la verja.<\/p>\n<p>En la tercera intervenci&oacute;n, realizada un a&ntilde;o despu&eacute;s de la segunda, se realiz&oacute; una operaci&oacute;n de limpieza y bru&ntilde;ido superficial del m&aacute;rmol tratado el a&ntilde;o anterior, se complet&oacute; la limpieza de detalles (cabezas de los faunos, volutas de las columnillas, cabezas de leones, etc.)&nbsp; mediante amoladoras dremel provistas de cepillos de pl&aacute;stico duro y raspines manuales de diamante y se dio protecci&oacute;n superficial mediante emulsi&oacute;n jabonosa.<\/p>\n<p>En la cuarta intervenci&oacute;n, prevista para octubre de 2014, se tiene planeado terminar con las acumulaciones calc&aacute;reas que subsisten en el interior de las tazas de los niveles segundo y tercero, lo que se ha de hacer mediante rasquetas mec&aacute;nicas y manuales. Se revisar&aacute;n todos los rejuntes, procediendo a las reposiciones necesarias y se proceder&aacute; a la limpieza y bru&ntilde;ido generalizados del m&aacute;rmol, con lijas diamantadas de grano fino, y a su protecci&oacute;n superficial con emulsi&oacute;n jabonosa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&iquest;Qu&eacute; valor diferencial tienen esta t&eacute;cnica en el &aacute;mbito de la restauraci&oacute;n?<\/strong><\/p>\n<p>Cada proyecto de conservaci&oacute;n-restauraci&oacute;n que planteamos tiene elementos comunes con otros realizados o conocidos, pero tambi&eacute;n elementos nuevos a resolver. Por ejemplo: algunas de nuestras fuentes de m&aacute;rmol se encuentran bajo grandes &aacute;rboles, en el caso de la fuente de la Plaza del Adelantado predominan los laureles de indias cuyos frutos maduros pueden manchar mucho el m&aacute;rmol en el caso de que tenga el poro superficial abierto. Por tanto es b&aacute;sico aplicar un satinado intenso y una protecci&oacute;n superficial de amplia cobertura, al menos en las superficies sobre las que pueden impactar directamente los frutos. Otro ejemplo, referido a las condiciones ambientales espec&iacute;ficas en que se encuentra el objeto patrimonial y su relaci&oacute;n con la elecci&oacute;n de t&eacute;cnicas concretas de pegado o rejunte: no se puede tratar igual un elemento ubicado en Santa Cruz y a pleno sol que otro situado en La Laguna y en lugar sombr&iacute;o.<\/p>\n<p><strong>&iquest;Qu&eacute; aprender&aacute;n los estudiantes que participan en esta intervenci&oacute;n? <\/strong><\/p>\n<p>Lo m&aacute;s importante es que aprender&aacute;n a ser respetuosos con el bien patrimonial sobre el que actuar&aacute;n y a razonar antes de actuar.<\/p>\n<p>Tenemos un problema de limpieza en el que tiene singular importancia la eliminaci&oacute;n de costras de carbonatos depositadas por el agua, pero el m&aacute;rmol es muy sensible a los productos qu&iacute;micos que actuar&iacute;an sobre dichas costras calc&aacute;reas, ya que es b&aacute;sicamente carbonato c&aacute;lcico. Es tambi&eacute;n muy delicado frente a los impactos debido a su estructura cristalina y puede rayarse con facilidad debido a su nivel medio de dureza. Es imprescindible establecer protocolos l&oacute;gicos de actuaci&oacute;n y analizar sus posibles consecuencias antes de aplicarlos.<\/p>\n<p>Los estudiantes que intervienen en el proyecto deben entender la importancia de los conocimientos que han adquirido en las diversas asignaturas cursadas durante sus estudios, entre ellas las referidas a criterios de intervenci&oacute;n sobre bienes patrimoniales, naturaleza de los materiales, t&eacute;cnicas de aplicaci&oacute;n, normas de seguridad, etc.<\/p>\n<p>Tambi&eacute;n debe resultar evidente la necesidad de seguir de manera sistem&aacute;tica los protocolos de actuaci&oacute;n establecidos; as&iacute; como la importancia que tiene calcular bien los tiempos para las diversas tareas de modo que puedan completar lo proyectado. &nbsp;<\/p>\n<p>Igualmente se acostumbran al trabajo en equipo, estableciendo din&aacute;micas de comportamiento que permitan equilibrar las tareas y evitar confrontaciones. Y al desarrollarse este proyecto en un lugar p&uacute;blico muy concurrido y sin vallas que nos separen de la poblaci&oacute;n, los estudiantes se encontrar&aacute;n tambi&eacute;n con la necesidad de escuchar y atender en lo posible a las personas que se acercan para observar, comentar, preguntar? dando respuestas adecuadas y atendiendo con amabilidad a los vecinos y visitantes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&iquest;Qu&eacute; formaci&oacute;n se ofrece con este tipo de intervenciones a los titulados de Bellas Artes en los &aacute;mbitos de la conservaci&oacute;n y la restauraci&oacute;n? <\/strong><\/p>\n<p>En general, los estudios de las diversas especialidades de Bellas Artes, siempre han tenido una amplia formaci&oacute;n pr&aacute;ctica, no obstante, como ocurre en cualquier otro &aacute;rea, nuestros estudiantes han de completar los aprendizajes te&oacute;ricos y t&eacute;cnicos que han tenido durante la carrera con la pr&aacute;ctica laboral y ser&aacute; esta la que les lleve a establecer modos de actuaci&oacute;n con resultados &oacute;ptimos.<\/p>\n<p>La participaci&oacute;n en este proyecto, aunque su duraci&oacute;n sea s&oacute;lo de un mes, les pone en contacto con el mundo laboral y todo lo que conlleva en cuanto a circunstancias concretas de desarrollo del trabajo, interrelaci&oacute;n con los compa&ntilde;eros de equipo, etc. &nbsp;&nbsp;<\/p>\n<p>Se ha de tener en cuenta tambi&eacute;n que el hecho de enfrentarse a un caso real, a una obra valorada y apreciada por la poblaci&oacute;n, conlleva un nivel de exigencia y de responsabilidad con el que no se ha enfrentado todav&iacute;a el alumno que ha trabajado &uacute;nicamente pruebas t&eacute;cnicas dise&ntilde;adas para el aprendizaje pero sin valor hist&oacute;rico alguno.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&iquest;Qu&eacute; resultado espera de las labores de limpieza que se van a acometer pr&oacute;ximamente?<\/strong><\/p>\n<p>Igual que en trabajos anteriores, espero que el objeto patrimonial quede en las mejores condiciones posibles en cuanto a su aspecto y pueda cumplir la funci&oacute;n ornamental que le es propia, pero sobre todo me preocupa que nuestra actuaci&oacute;n sea respetuosa con la naturaleza del elemento y sirva para aumentar su resistencia de cara a los diversos agentes que inciden sobre &eacute;l, que nuestra actuaci&oacute;n ayude a mantenerlo mejor de cara al futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La catedr&aacute;tica de Escultura de la ULL, responsable del proyecto de restauraci&oacute;n de Fuente de la conocida plaza lagunera, contesta a una serie de cuestiones sobre su labor investigadora y el valor de este tipo de trabajos para la sociedad y para los estudiantes que colaboran en ellos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":36,"featured_media":14502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[173],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/2285_xh_2012_11_16-225x300.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/14503"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=14503"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/14503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/14502"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=14503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=14503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=14503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}