{"id":11975,"date":"2013-07-30T20:24:33","date_gmt":"2013-07-30T20:24:33","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=11975"},"modified":"2013-07-30T20:24:33","modified_gmt":"2013-07-30T20:24:33","slug":"publicado-el-primer-listado-provisional-de-la-oferta-de-empleo-como-gestor-junior-a-tiempo-parcial-en-la-fundacion-general-de-la-universidad-de-la-laguna-municipio-de-adeje","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/30\/publicado-el-primer-listado-provisional-de-la-oferta-de-empleo-como-gestor-junior-a-tiempo-parcial-en-la-fundacion-general-de-la-universidad-de-la-laguna-municipio-de-adeje\/","title":{"rendered":"Publicado el primer listado provisional de la oferta de empleo como gestor junior a tiempo parcial en la Fundaci\u00f3n General de la Universidad de La Laguna municipio de Adeje"},"content":{"rendered":"<p style='text-align: justify'>Se abre un periodo de alegaciones que finaliza a las 23:59h. del&nbsp;01 de agosto de 2013, se proceder&aacute; a publicar el listado definitivo el&nbsp;02 de agosto de 2013.<\/p>\n<p><\/p>\n<p style='text-align: justify'>A continuaci&oacute;n se presenta el primer listado provisional de aceptados\/as y excluidos\/a&nbsp;con su motivo de la selecci&oacute;n de personal para para cubrir una plaza como gestor junior en el municipio de Adeje.<\/p>\n<p style='text-align: justify'><a title='Listado provisional aceptados y excluidos - Adeje' href='..\/..\/public\/docs\/852_ad_1_listado_provisional_aceptados_y_excluidos__perfil_gestor_junior_adeje.pdf' target='_blank' rel=\"noopener noreferrer\">(Consulta el listado provisional aqu&iacute;)<\/a><\/p>\n<p style='text-align: justify'>A partir de este momento, comienza el periodo de alegaciones, <strong>en ning&uacute;n caso<\/strong>, ser&aacute; per&iacute;odo de subsanaci&oacute;n de documentaci&oacute;n. Finalizado &eacute;ste, a las 23:59h. del&nbsp;01 de agosto de 2013, y resueltas las alegaciones se proceder&aacute; &nbsp;a publicar el primer listado definitivo. En el listado definitivo, se especificar&aacute;n las candidaturas que han superado la primera fase de selecci&oacute;n, adem&aacute;s de los horarios:<\/p>\n<p style='text-align: justify'>a. De realizaci&oacute;n de las pruebas que considere oportuno el comit&eacute; de selecci&oacute;n.<\/p>\n<p style='text-align: justify'>b. Para la entrega de la documentaci&oacute;n acreditativa de los m&eacute;ritos expuestos.<\/p>\n<p style='text-align: justify'>Puede consultar las bases de la presente convocatoria:<\/p>\n<p style='text-align: justify'><a title='Bases generales' href='..\/..\/public\/docs\/823_zg_bases_generales.pdf' target='_blank' rel=\"noopener noreferrer\">Bases generales.<\/a><\/p>\n<p style='text-align: justify'><a title='Bases espec&iacute;ficas' href='..\/..\/public\/docs\/843_2j_bases_especificas.pdf' target='_blank' rel=\"noopener noreferrer\">Bases espec&iacute;ficas<\/a>.<\/p>\n<p><a title='Anexo - documento de alegaciones' href='..\/..\/public\/docs\/833_l3_documento_de_alegaciones.docx' target='_blank' rel=\"noopener noreferrer\">Documento de alegaciones<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style='text-align: justify'>Se abre un periodo de alegaciones que finaliza a las 23:59h. del&nbsp;01 de agosto de 2013, se proceder&aacute; a publicar el listado definitivo el&nbsp;02 de agosto de 2013.<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[173,518,671,672,1066],"featured_image_thumbnail_url":null,"_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11975"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=11975"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11975\/revisions"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=11975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=11975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=11975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}