{"id":11953,"date":"2013-07-22T22:52:38","date_gmt":"2013-07-22T22:52:38","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=11953"},"modified":"2013-07-22T22:52:38","modified_gmt":"2013-07-22T22:52:38","slug":"se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/","title":{"rendered":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna"},"content":{"rendered":"<p style='text-align: justify'>El periodo para las inscripciones, que deber&aacute;n realizarse a trav&eacute;s de la     sede  electr&oacute;nica de la Fundaci&oacute;n, finaliza el 26 de julio de 2013.<\/p>\n<p><\/p>\n<div>\n<p style='text-align: justify'>La Fundaci&oacute;n General de la Universidad de La Laguna renueva la bolsa de becarios\/as para el apoyo en el desarrollo de funciones de administraci&oacute;n y procede a  publicar las bases   generales y  espec&iacute;ficas para la convocatoria que  regula el  procedimiento  de  selecci&oacute;n.<\/p>\n<p style='text-align: justify'>Para la    inscripci&oacute;n es totalmente necesario el cumplimiento de los requisitos  y   de lo expuesto en las bases que se presentan a continuaci&oacute;n.<\/p>\n<p style='text-align: justify'>Puedes ver las bases en:<\/p>\n<p style='text-align: justify'><a title='Bases generales' href='..\/..\/public\/docs\/846_ap_bases_generales.pdf' target='_blank' rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Bases generales.<\/a><\/p>\n<p style='text-align: justify'><a title='Bases espec&iacute;ficas' href='..\/..\/public\/docs\/847_r3_bases_especificas.pdf' target='_blank' rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">Bases espec&iacute;ficas<\/a>.<\/p>\n<p style='text-align: justify'>Puede tramitar su inscripci&oacute;n en este <a title='Oferta de empleo' href='https:\/\/sede.fg.ull.es\/es\/empleo\/detalle\/a13220001\/fundacion-general-de-la-universidad-de-la-laguna' target='_blank' rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p style='text-align: justify'>El periodo para las inscripciones, que deber&aacute;n realizarse a trav&eacute;s de la     sede  electr&oacute;nica de la Fundaci&oacute;n, finaliza el 26 de julio de 2013.<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6],"tags":[173,230,518],"class_list":["post-11953","post","type-post","status-publish","format-standard","hentry","category-empleo","category-fundacion","tag-archivados","tag-becas","tag-empleo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"og:description\" content=\"El periodo para las inscripciones, que deber&aacute;n realizarse a trav&eacute;s de la   sede electr&oacute;nica de la Fundaci&oacute;n, finaliza el 26 de julio de 2013.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/\" \/>\n<meta property=\"og:site_name\" content=\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-22T22:52:38+00:00\" \/>\n<meta name=\"author\" content=\"fgull\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fgull\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/\"},\"author\":{\"name\":\"fgull\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"headline\":\"Se renueva la bolsa de becarios\\\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna\",\"datePublished\":\"2013-07-22T22:52:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/\"},\"wordCount\":154,\"keywords\":[\"Archivados\",\"Becas\",\"Empleo\"],\"articleSection\":[\"Empleo\",\"Fundaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/\",\"name\":\"Se renueva la bolsa de becarios\\\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\"},\"datePublished\":\"2013-07-22T22:52:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/22\\\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se renueva la bolsa de becarios\\\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\",\"name\":\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\",\"name\":\"fgull\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"caption\":\"fgull\"},\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/author\\\/fgull\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/","og_locale":"es_ES","og_type":"article","og_title":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","og_description":"El periodo para las inscripciones, que deber&aacute;n realizarse a trav&eacute;s de la   sede electr&oacute;nica de la Fundaci&oacute;n, finaliza el 26 de julio de 2013.","og_url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/","og_site_name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","article_published_time":"2013-07-22T22:52:38+00:00","author":"fgull","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fgull","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/#article","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/"},"author":{"name":"fgull","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"headline":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna","datePublished":"2013-07-22T22:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/"},"wordCount":154,"keywords":["Archivados","Becas","Empleo"],"articleSection":["Empleo","Fundaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/","url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/","name":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#website"},"datePublished":"2013-07-22T22:52:38+00:00","author":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"breadcrumb":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/22\/se-renueva-la-bolsa-de-becariosas-para-el-apoyo-en-desarrollo-de-funciones-administrativas-en-la-fundacion-general-de-la-universidad-de-la-laguna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fg.ull.es\/hemeroteca\/"},{"@type":"ListItem","position":2,"name":"Se renueva la bolsa de becarios\/as para el apoyo en desarrollo de funciones administrativas en la Fundaci\u00f3n General de la Universidad de La Laguna"}]},{"@type":"WebSite","@id":"https:\/\/fg.ull.es\/hemeroteca\/#website","url":"https:\/\/fg.ull.es\/hemeroteca\/","name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fg.ull.es\/hemeroteca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238","name":"fgull","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","caption":"fgull"},"url":"https:\/\/fg.ull.es\/hemeroteca\/author\/fgull\/"}]}},"featured_image_thumbnail_url":"","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=11953"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11953\/revisions"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=11953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=11953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=11953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}