{"id":11923,"date":"2013-07-18T11:39:41","date_gmt":"2013-07-18T11:39:41","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=11923"},"modified":"2013-07-18T11:39:41","modified_gmt":"2013-07-18T11:39:41","slug":"utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/","title":{"rendered":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible"},"content":{"rendered":"<p style='text-align: justify'>El pasado martes 16 de julio se impartieron varias ponencias en la Universidad de Verano de Adeje en las que se demostr&oacute; al alumnado las posibilidades que tienen las herramientas tecnol&oacute;gicas en el plano de la educaci&oacute;n f&iacute;sica.<\/p>\n<p><\/p>\n<p style='text-align: justify'>El martes 16 de julio se desarrollaron en la Universidad de Verano de Adeje dos ponencias de forma paralela. Se trat&oacute; de las charlas impartidas por Patricia Pintor D&iacute;az y &Aacute;ngeles Judith Hern&aacute;ndez S&aacute;nchez, Doctora En Educaci&oacute;n F&iacute;sica y Licenciada en Educaci&oacute;n F&iacute;sica y Filosof&iacute;a y letras y Licenciada en Ciencias de la Actividad F&iacute;sica y el Deporte, respectivamente, quienes a lo largo de la jornada demostraron al alumnado las posibilidades que tienen las herramientas tecnol&oacute;gicas en el plano de la educaci&oacute;n f&iacute;sica y aseguraron que &ldquo;no podemos rechazar el m&oacute;vil porque actualmente se ha convertido en una herramienta b&aacute;sica, es como tener un libro abierto constantemente&rdquo;.<\/p>\n<p style='text-align: justify'>Ambas expertas manifestaron que &ldquo;actualmente todos tenemos al alcance esta tecnolog&iacute;a que podemos utilizar y emplear de forma correcta en el incremento de los niveles de la actividad f&iacute;sica. Hacer un uso positivo de estos medios no es tarea dif&iacute;cil, simplemente hace falta orientaci&oacute;n y &ldquo;para eso esta el profesorado&rdquo;.<\/p>\n<p style='text-align: justify'>Los m&oacute;viles, tabletas, smartphones, etc, son ordenadores port&aacute;tiles que aportan muchas cosas, no solo sirven para chatear, tambi&eacute;n podemos extraer de ellos una utilidad mayor tales como: descargar aplicaciones que ayuden al mejor rendimiento f&iacute;sico del alumnado, a la mejora de su condici&oacute;n f&iacute;sica, de sus tiempos en carrera, a la correcci&oacute;n de sus movimientos en caso de que grabaran cualquier actividad&rdquo;.<\/p>\n<p style='text-align: justify'>En este apartado, comentaron que ya han desarrollado experiencias pilotos en institutos de ense&ntilde;anza donde el alumnado se ha grabado realizando una pr&aacute;ctica de expresi&oacute;n o trabajo con cuerdas dobles y una vez finalizado y visualizado el v&iacute;deo, pueden determinar y corregir los fallos que han cometido al o largo del ejercicio, por lo tanto, el aprendizaje se hace en el momento al igual que la mejora de cada ejercicio. De esta forma, aseguran las profesoras &ldquo;potenciamos de forma positiva al conjunto de alumnos&rdquo;.<\/p>\n<p style='text-align: justify'><strong>Trabajo coordinado<\/strong><\/p>\n<p style='text-align: justify'>Pintor D&iacute;az y Hern&aacute;ndez S&aacute;nchez coincidieron en que lo mejor es trabajar de forma coordinada y transversal, es decir, unificar varias asignaturas en un trabajo conjunto, &ldquo;hemos detectado que cada vez que planteamos una actividad con esta modalidad, la aceptaci&oacute;n de la misma es muy positiva, los chicos y las chicas se motivan much&iacute;simo m&aacute;s porque, adem&aacute;s de realizar una tarea que les es grata y f&aacute;cil de realizar, se desarrolla una competitividad sana y al mismo tiempo, aprenden la importancia de trabajar en equipo&rdquo;.<\/p>\n<p style='text-align: justify'>Finalmente, las docentes concluyeron que &ldquo;la clave para que la participaci&oacute;n estudiantil participe es organizar siempre propuestas que tengan un objetivo a lograr, por ejemplo: carreras solidarias o ben&eacute;ficas cuya recaudaci&oacute;n sea dirigida a personas u organizaciones que lo necesiten&#8217;.<\/p>\n<p style='text-align: right'>*Nota cedida por el Ayto. de Adeje<\/p>\n","protected":false},"excerpt":{"rendered":"<p style='text-align: justify'>El pasado martes 16 de julio se impartieron varias ponencias en la Universidad de Verano de Adeje en las que se demostr&oacute; al alumnado las posibilidades que tienen las herramientas tecnol&oacute;gicas en el plano de la educaci&oacute;n f&iacute;sica.<\/p>\n","protected":false},"author":36,"featured_media":11922,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[173,672,1424],"class_list":["post-11923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion","tag-archivados","tag-formacion","tag-universidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"og:description\" content=\"El pasado martes 16 de julio se impartieron varias ponencias en la Universidad de Verano de Adeje en las que se demostr&oacute; al alumnado las posibilidades que tienen las herramientas tecnol&oacute;gicas en el plano de la educaci&oacute;n f&iacute;sica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/\" \/>\n<meta property=\"og:site_name\" content=\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-18T11:39:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fgull\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fgull\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/\"},\"author\":{\"name\":\"fgull\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"headline\":\"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible\",\"datePublished\":\"2013-07-18T11:39:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/\"},\"wordCount\":590,\"image\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1438_7t_94220130716133245.jpg\",\"keywords\":[\"Archivados\",\"Formaci\u00f3n\",\"Universidad\"],\"articleSection\":[\"Formaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/\",\"name\":\"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1438_7t_94220130716133245.jpg\",\"datePublished\":\"2013-07-18T11:39:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1438_7t_94220130716133245.jpg\",\"contentUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1438_7t_94220130716133245.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/18\\\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\",\"name\":\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\",\"name\":\"fgull\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"caption\":\"fgull\"},\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/author\\\/fgull\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/","og_locale":"es_ES","og_type":"article","og_title":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","og_description":"El pasado martes 16 de julio se impartieron varias ponencias en la Universidad de Verano de Adeje en las que se demostr&oacute; al alumnado las posibilidades que tienen las herramientas tecnol&oacute;gicas en el plano de la educaci&oacute;n f&iacute;sica.","og_url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/","og_site_name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","article_published_time":"2013-07-18T11:39:41+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg","type":"image\/jpeg"}],"author":"fgull","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fgull","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#article","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/"},"author":{"name":"fgull","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"headline":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible","datePublished":"2013-07-18T11:39:41+00:00","mainEntityOfPage":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/"},"wordCount":590,"image":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#primaryimage"},"thumbnailUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg","keywords":["Archivados","Formaci\u00f3n","Universidad"],"articleSection":["Formaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/","url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/","name":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#primaryimage"},"image":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#primaryimage"},"thumbnailUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg","datePublished":"2013-07-18T11:39:41+00:00","author":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"breadcrumb":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#primaryimage","url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg","contentUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/18\/utilizar-la-tecnologia-para-mejorar-los-niveles-de-actividad-fisica-y-deportiva-ya-es-posible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fg.ull.es\/hemeroteca\/"},{"@type":"ListItem","position":2,"name":"Utilizar la tecnolog\u00eda para mejorar los niveles de actividad f\u00edsica y deportiva ya es posible"}]},{"@type":"WebSite","@id":"https:\/\/fg.ull.es\/hemeroteca\/#website","url":"https:\/\/fg.ull.es\/hemeroteca\/","name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fg.ull.es\/hemeroteca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238","name":"fgull","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","caption":"fgull"},"url":"https:\/\/fg.ull.es\/hemeroteca\/author\/fgull\/"}]}},"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1438_7t_94220130716133245-300x200.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=11923"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/11922"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=11923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=11923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=11923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}