{"id":11902,"date":"2013-07-15T14:58:03","date_gmt":"2013-07-15T14:58:03","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=11902"},"modified":"2013-07-15T14:58:03","modified_gmt":"2013-07-15T14:58:03","slug":"emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/","title":{"rendered":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico"},"content":{"rendered":"<p style='text-align: justify'>El Ciclo de P&iacute;ldoras Formativas celebra su cuarta sesi&oacute;n el pr&oacute;ximo 24 de julio en el Aulario de la FGULL.<\/p>\n<p><\/p>\n<p style='text-align: justify'>El programa Emprende.ull de la Fundaci&oacute;n General de la Universidad de La Laguna ha puesto en marcha el Ciclo de P&iacute;ldoras Formativas 2013 que consta de cuatro sesiones formativas, de las que ya se han celebrado tres, acerca de temas como el social media y la comunicaci&oacute;n digital, fiscalidad bancaria y la contabilidad para el emprendedor. Estas actividades tienen car&aacute;cter totalmente <strong><span style='text-decoration: underline'>gratuito<\/span><\/strong> y pretenden formar a los emprendedores participantes en metodolog&iacute;as m&aacute;s experienciales y pr&aacute;cticas.<\/p>\n<p style='text-align: justify'>Entre estas sesiones, se encuentra la &uacute;ltima que tendr&aacute; lugar dentro de la celebraci&oacute;n de este ciclo, que se celebrar&aacute; el pr&oacute;ximo mi&eacute;rcoles 24 de julio y que estar&aacute; dedicada a la contabilidad, fiscalidad y el laboral b&aacute;sico para emprendedores. Tendr&aacute; lugar en el aula C 2.04 de la segunda planta de la FGULL en horario de 16 a 19 horas.<\/p>\n<p style='text-align: justify'>El objetivo de esta formaci&oacute;n es capacitar a los asistentes en conocimientos, informaci&oacute;n y herramientas b&aacute;sicas para entender la situaci&oacute;n empresarial desde el punto de vista fiscal, contable y laboral que puede afectar a los emprendedores.<\/p>\n<p style='text-align: justify'>La metodolog&iacute;a utilizada ser&aacute; eminentemente pr&aacute;ctica y participativa, basada en el trabajo de los participantes en casos reales.<\/p>\n<p style='text-align: justify'><a href='https:\/\/sede.fg.ull.es\/es\/emprendimiento\/detalle\/a12040214\/ciclo-pildoras-formativas-cuarta-fiscalidad-contabilidad-y-laboral-basico-para-el-emprendedor' target=\"_blank\" rel=\"noopener\">(M&aacute;s informaci&oacute;n e inscripci&oacute;n aqu&iacute;)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p style='text-align: justify'>El Ciclo de P&iacute;ldoras Formativas celebra su cuarta sesi&oacute;n el pr&oacute;ximo 24 de julio en el Aulario de la FGULL.<\/p>\n","protected":false},"author":36,"featured_media":11901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[173,425,672,1424],"class_list":["post-11902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion","tag-archivados","tag-cursos","tag-formacion","tag-universidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"og:description\" content=\"El Ciclo de P&iacute;ldoras Formativas celebra su cuarta sesi&oacute;n el pr&oacute;ximo 24 de julio en el Aulario de la FGULL.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/\" \/>\n<meta property=\"og:site_name\" content=\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-15T14:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"648\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fgull\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fgull\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/\"},\"author\":{\"name\":\"fgull\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"headline\":\"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico\",\"datePublished\":\"2013-07-15T14:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/\"},\"wordCount\":286,\"image\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg\",\"keywords\":[\"Archivados\",\"Cursos\",\"Formaci\u00f3n\",\"Universidad\"],\"articleSection\":[\"Formaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/\",\"name\":\"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg\",\"datePublished\":\"2013-07-15T14:58:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg\",\"contentUrl\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2015\\\/04\\\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg\",\"width\":648,\"height\":930},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/2013\\\/07\\\/15\\\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#website\",\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/\",\"name\":\"Hist\u00f3rico de noticias de la Fundaci\u00f3n General\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/#\\\/schema\\\/person\\\/cf424320c3c543ecb9f15d3785219238\",\"name\":\"fgull\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g\",\"caption\":\"fgull\"},\"url\":\"https:\\\/\\\/fg.ull.es\\\/hemeroteca\\\/author\\\/fgull\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/","og_locale":"es_ES","og_type":"article","og_title":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","og_description":"El Ciclo de P&iacute;ldoras Formativas celebra su cuarta sesi&oacute;n el pr&oacute;ximo 24 de julio en el Aulario de la FGULL.","og_url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/","og_site_name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","article_published_time":"2013-07-15T14:58:03+00:00","og_image":[{"width":648,"height":930,"url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg","type":"image\/jpeg"}],"author":"fgull","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fgull","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#article","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/"},"author":{"name":"fgull","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"headline":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico","datePublished":"2013-07-15T14:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/"},"wordCount":286,"image":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#primaryimage"},"thumbnailUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg","keywords":["Archivados","Cursos","Formaci\u00f3n","Universidad"],"articleSection":["Formaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/","url":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/","name":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico - Hist\u00f3rico de noticias de la Fundaci\u00f3n General","isPartOf":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#primaryimage"},"image":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#primaryimage"},"thumbnailUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg","datePublished":"2013-07-15T14:58:03+00:00","author":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238"},"breadcrumb":{"@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#primaryimage","url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg","contentUrl":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg.jpg","width":648,"height":930},{"@type":"BreadcrumbList","@id":"https:\/\/fg.ull.es\/hemeroteca\/2013\/07\/15\/emprende-ull-continua-con-las-pildoras-formativas-acercando-a-los-emprendedores-temas-como-la-contabilidad-fiscalidad-y-el-laboral-basico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fg.ull.es\/hemeroteca\/"},{"@type":"ListItem","position":2,"name":"Emprende.ull contin\u00faa con las P\u00edldoras Formativas acercando a los emprendedores temas como la contabilidad, fiscalidad y el laboral b\u00e1sico"}]},{"@type":"WebSite","@id":"https:\/\/fg.ull.es\/hemeroteca\/#website","url":"https:\/\/fg.ull.es\/hemeroteca\/","name":"Hist\u00f3rico de noticias de la Fundaci\u00f3n General","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fg.ull.es\/hemeroteca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fg.ull.es\/hemeroteca\/#\/schema\/person\/cf424320c3c543ecb9f15d3785219238","name":"fgull","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b3f179500dd91d295ffa66543a853574e5676c5c7f8b31d00af1a80aadcafa4?s=96&d=mm&r=g","caption":"fgull"},"url":"https:\/\/fg.ull.es\/hemeroteca\/author\/fgull\/"}]}},"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/1433_ux_ciclo_de_pildoras_formativas_2013_de_emprendeulljpg-209x300.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=11902"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/11902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/11901"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=11902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=11902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=11902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}