{"id":10604,"date":"2012-10-26T16:57:52","date_gmt":"2012-10-26T16:57:52","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=10604"},"modified":"2012-10-26T16:57:52","modified_gmt":"2012-10-26T16:57:52","slug":"nuevo-curso-del-servicio-de-idiomas-introduccion-a-la-lengua-de-signos-espanola","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2012\/10\/26\/nuevo-curso-del-servicio-de-idiomas-introduccion-a-la-lengua-de-signos-espanola\/","title":{"rendered":"Nuevo curso del Servicio de Idiomas: &#039;Introducci\u00f3n a la Lengua de Signos Espa\u00f1ola&#039;"},"content":{"rendered":"<p>El Servicio de Idiomas de la ULL incorpora una nueva lengua a su oferta con este curso: &#8216;Introducci\u00f3n a la Lengua de Signos Espa\u00f1ola&#8217;. Consta de 20 horas y se impartir\u00e1 tanto en La Laguna como en Adeje.<\/p>\n<p>A partir del pr&oacute;ximo d&iacute;a 19 de noviembre el <a href='..\/..\/es\/proyecto\/servicio_de_idiomas_de_la_universidad_de_la_laguna\/5\/'>Servicio de Idiomas de la Universidad de La Laguna<\/a> incorporar&aacute; el estudio de la Lengua de Signos Espa&ntilde;ola con un primer curso. La formaci&oacute;n ser&aacute; de car&aacute;cter introductorio y se podr&aacute; realizar en cualquiera de las dos sedes del Servicio de Idiomas de las ULL, en La Laguna o en Adeje.<\/p>\n<p>El <strong>curso de La Laguna<\/strong> se desarrollar&aacute; entre el 19 de noviembre y el 12 de diciembre, los lunes y mi&eacute;rcoles, de 19 a 21.30 horas en el aulario de la Fundaci&oacute;n Empresa Universidad de La Laguna. <a href='https:\/\/servicios.feu.ull.es\/Portal\/ExpedienteOfertado.aspx?COD=A12030271'>Toda la informaci&oacute;n y acceso a la matr&iacute;cula aqu&iacute;<\/a>.<\/p>\n<p>En<strong> Adeje <\/strong>el curso comenzar&aacute; el 20 de noviembre y terminar&aacute; el 13 de diciembre, imparti&eacute;ndose los martes y jueves de 16 a 18.30 horas. <a href='https:\/\/servicios.feu.ull.es\/Portal\/ExpedienteOfertado.aspx?COD=A12030279'>Toda la informaci&oacute;n y acceso a la matr&iacute;cula aqu&iacute;.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio de Idiomas de la ULL incorpora una nueva lengua a su oferta con este curso: &#8216;Introducci\u00f3n a la Lengua de Signos Espa\u00f1ola&#8217;. Consta de 20 horas y se impartir\u00e1 tanto en La Laguna como en Adeje.<\/p>\n","protected":false},"author":36,"featured_media":10603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[173,672,780,1424],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/966_7p_cartel_lse-212x300.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10604"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=10604"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/10603"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=10604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=10604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=10604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}