{"id":10565,"date":"2012-10-17T17:42:43","date_gmt":"2012-10-17T17:42:43","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=10565"},"modified":"2012-10-17T17:42:43","modified_gmt":"2012-10-17T17:42:43","slug":"arranca-el-programa-integral-de-apoyo-a-la-innovacion-y-competitividad-de-la-pyme-canaria","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2012\/10\/17\/arranca-el-programa-integral-de-apoyo-a-la-innovacion-y-competitividad-de-la-pyme-canaria\/","title":{"rendered":"Arranca el &#039;Programa Integral de Apoyo a la Innovaci\u00f3n y Competitividad de la Pyme Canaria&#039;"},"content":{"rendered":"<p>Los servicios 1 y 2: &#8216;Buenas pr\u00e1cticas en Innovaci\u00f3n-Crecimiento, Internacionalizaci\u00f3n&#8217;, ser\u00e1n gestionados a trav\u00e9s de las C\u00e1maras de Comercio, y el servicio 3, &#8216;Innovaci\u00f3n basada en el Conocimiento&#8217;, ser\u00e1 gestionado por las fundaciones universitarias.<\/p>\n<p style='text-align: left'>El <a href='http:\/\/competitividadpyme.sitios.feull.org\/'>&#8216;Programa Integral de Apoyo a la Innovaci&oacute;n y Competitividad de la Pyme Canaria&acute;<\/a> pretende impulsar la productividad del tejido empresarial canario, potenciando la transferencia y comercializaci&oacute;n de los resultados de la I D i y estimulando la capacidad innovadora de las pymes. Para su desarrollo, el Ejecutivo regional ha destinado un total de 1.387.599,85 euros y tiene por objeto caracterizar el nivel de innovaci&oacute;n y productividad de 1.400 pymes de las Islas para mejorar su competitividad a trav&eacute;s del an&aacute;lisis y el desarrollo de acciones formativas espec&iacute;ficas en materias relacionadas con la I D i, la valorizaci&oacute;n tecnol&oacute;gica y los instrumentos financieros de proyectos innovadores.<\/p>\n<p>En el acto de presentaci&oacute;n, celebrado el pasado martes 16 de octubre de 2012, en la sede de la<a href='http:\/\/agencia.itccanarias.org\/es\/index.jsp'> ACIISI<\/a> en Las Palmas de Gran Canaria, han participado tambi&eacute;n representantes de las entidades implicadas en la ejecuci&oacute;n de los distintos servicios que integra el programa: Vicente Dorta y Mauro Manuel Fern&aacute;ndez Felipe, director de la C&aacute;mara de Comercio, Industria y Navegaci&oacute;n de Santa Cruz de Tenerife y presidente de la delegaci&oacute;n de la C&aacute;mara en la Isla de La Palma, respectivamente; Isabel Quevedo, directora de la C&aacute;mara de Comercio, Industria y Navegaci&oacute;n de Lanzarote; Sonia Camino M&aacute;rquez, secretaria general de la C&aacute;mara de Comercio de Fuerteventura; Pilar Alcaide, directora de la C&aacute;mara de Comercio de Gran Canaria; Sergio Alonso, gerente de la Fundaci&oacute;n Empresa Universidad de La Laguna, y Eduardo Manrique de Lara, gerente de la Fundaci&oacute;n Universitaria de Las Palmas.<\/p>\n<p>Con la puesta en marcha del &#8216;Programa Integral de Apoyo a la Innovaci&oacute;n y Competitividad de la Pyme Canaria&acute;, en el que colabora el <a href='http:\/\/www.itccanarias.org\/web\/?lang=es'>Instituto Tecnol&oacute;gico de Canarias (ITC)<\/a>, el Gobierno de Canarias pretende impulsar la productividad del tejido empresarial canario, potenciando la transferencia y comercializaci&oacute;n de los resultados de la I D i y estimulando la capacidad innovadora de las pymes canarias.<\/p>\n<p>Durante la presentaci&oacute;n de esta iniciativa, Juan Ruiz Alzola, director de la ACIISI, dijo que la importancia del programa radica en que `va a permitir analizar la situaci&oacute;n de nuestras pymes y entender mejor en qu&eacute; punto se encuentra la innovaci&oacute;n en nuestro tejido productivo, para proponer medidas concretas de apoyo al desarrollo empresarial&acute;.<\/p>\n<p>En este sentido detall&oacute; los trabajos que cada uno de los agentes implicados van a llevar a cabo para desarrollar con &eacute;xito el programa, destacando que `es fundamental impulsar procesos de crecimiento empresarial, con voluntad de externalizar nuestra producci&oacute;n&acute;. Las c&aacute;maras de comercio trabajar&aacute;n con 1.200 empresas de las Islas, y las fundaciones universitarias, por su parte, lo har&aacute;n con 100 empresas intensivas en conocimiento, 50 en cada provincia, tarea &eacute;sta que requiere la m&aacute;xima coordinaci&oacute;n con las universidades y centros p&uacute;blicos de investigaci&oacute;n.<\/p>\n<p>Por &uacute;ltimo, Eduardo Manrique de Lara, en nombre de las dos fundaciones universitarias, dijo que el trabajo de &eacute;stas `se ci&ntilde;e a empresas muy tecnol&oacute;gicas, con innovaci&oacute;n puntera&acute;, de ah&iacute; la necesidad de vincular a grupos de investigaci&oacute;n con empresas, para que les den todo el soporte. Destac&oacute; tambi&eacute;n la labor de focalizaci&oacute;n de `aquellas pymes que tengan experiencia de trabajar en el &aacute;mbito de la innovaci&oacute;n o vinculadas a sectores tecnol&oacute;gicos m&aacute;s punteros&acute;. Las Fundaciones realizar&aacute;n diagn&oacute;stico personalizado a cada una de las&nbsp; empresas participantes (50 por provincia) y les prestar&aacute;n asesoramiento personalizado.<\/p>\n<p><strong>Servicios a las empresas<\/strong><\/p>\n<p>El <a href='http:\/\/competitividadpyme.sitios.feull.org\/'>`Programa Integral de Apoyo a la Innovaci&oacute;n y Competitividad de la Pyme Canaria&acute; <\/a>est&aacute; integrado por tres servicios, siendo los servicios 1 y 2 &#8216;Buenas pr&aacute;cticas en Innovaci&oacute;n-Crecimiento, Internacionalizaci&oacute;n&#8217;, los que gestionar&aacute;n las C&aacute;maras de Comercio en las dos provincias canarias, y el servicio 3, &#8216;Innovaci&oacute;n basada en el Conocimiento&#8217;, el que gestionar&aacute;n las fundaciones empresa de las dos universidades canarias.<\/p>\n<p>Para su desarrollo, el Ejecutivo regional ha destinado un total de 1.387.599,85 euros, de los que 918.028,33 euros corresponden a la dotaci&oacute;n recibida por las C&aacute;maras de Comercio para ejecutar los servicios 1 y 2, mientras que 469.571,52 euros se han destinado a las dos fundaciones universitarias para la puesta en marcha del servicio 3.<\/p>\n<p>Los servicios 1 y 2: &#8216;Buenas pr&aacute;cticas en Innovaci&oacute;n-Crecimiento, Internacionalizaci&oacute;n&#8217; comprenden p&iacute;ldoras formativas para que 1.200 micropymes canarias se beneficien de peque&ntilde;as innovaciones y equilibren su productividad con la media comunitaria, as&iacute; como medidas de difusi&oacute;n y formaci&oacute;n, dirigidas a 100 pymes tradicionales con capacidad de crecimiento, para impulsar su internacionalizaci&oacute;n y el acceso a l&iacute;neas de financiaci&oacute;n para la puesta en marcha de sus proyectos.<\/p>\n<p>Por otro lado, el servicio 3 consiste en un programa formativo dirigido a 100 pymes de las Islas interesadas en conocer c&oacute;mo introducir la innovaci&oacute;n en sus procesos, aprender a gestionarla y c&oacute;mo materializar y llevar al mercado el valor generado. Concretamente, este servicio prev&eacute; el establecimiento de una estrategia personalizada en cada una de las 100 empresas beneficiarias, cincuenta en cada provincia, para que puedan adquirir las habilidades necesarias que les permitan mejorar sus procesos productivos. Esta estrategia comprende tanto formaci&oacute;n te&oacute;rica como formaci&oacute;n pr&aacute;ctica.<\/p>\n<p>El &#8216;Programa Integral de Apoyo a la Innovaci&oacute;n y Competitividad de la Pyme Canaria&#8217; es una actuaci&oacute;n dise&ntilde;ada e impulsada por la Agencia Canaria de Investigaci&oacute;n, Innovaci&oacute;n y Sociedad de la Informaci&oacute;n (ACIISI), con la colaboraci&oacute;n del Instituto Tecnol&oacute;gico de Canarias (ITC), cofinanciada por el Fondo Social Europeo, en el marco del Programa Operativo FSE de Canarias 2007-2013.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los servicios 1 y 2: &#8216;Buenas pr\u00e1cticas en Innovaci\u00f3n-Crecimiento, Internacionalizaci\u00f3n&#8217;, ser\u00e1n gestionados a trav\u00e9s de las C\u00e1maras de Comercio, y el servicio 3, &#8216;Innovaci\u00f3n basada en el Conocimiento&#8217;, ser\u00e1 gestionado por las fundaciones universitarias.<\/p>\n","protected":false},"author":36,"featured_media":10564,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[173,649,821,1203],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/953_de_foto_presentacion_prgo_innov_competitividad.jpg","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10565"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=10565"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/10564"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=10565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=10565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=10565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}