{"id":10094,"date":"2012-05-31T11:49:30","date_gmt":"2012-05-31T11:49:30","guid":{"rendered":"http:\/\/www.fg.ull.es\/?p=10094"},"modified":"2012-05-31T11:49:30","modified_gmt":"2012-05-31T11:49:30","slug":"el-servicio-de-idiomas-de-la-universidad-de-la-laguna-presenta-su-oferta-formativa-de-cursos-intensivos-de-verano","status":"publish","type":"post","link":"https:\/\/fg.ull.es\/hemeroteca\/2012\/05\/31\/el-servicio-de-idiomas-de-la-universidad-de-la-laguna-presenta-su-oferta-formativa-de-cursos-intensivos-de-verano\/","title":{"rendered":"El Servicio de Idiomas de la Universidad de La Laguna presenta su oferta formativa de cursos intensivos de verano"},"content":{"rendered":"<p>Se convocan 25 becas &#8216;Prolingua&#8217;, financiadas por el Gobierno de Canarias, que permitir\u00e1n costear gran parte del precio de los cursos. El plazo de solicitud para las becas se cierra el 8 de junio.<\/p>\n<p><strong><em> <\/em><\/strong>M&aacute;s de cuarenta cursos de idiomas formar&aacute;n parte de la oferta formativa del<a href='..\/..\/es\/proyecto\/servicio_de_idiomas_de_la_universidad_de_la_laguna\/5\/'> Servicio de Idiomas de la ULL.<\/a> Se impartir&aacute;n a partir de este mes de junio, tanto en la sede de La Laguna como en el <a href='..\/..\/es\/proyecto\/servicio_de_idiomas_ull_adeje\/49\/2\/'>Campus de Adeje<\/a>.<\/p>\n<p>La sede de La Laguna acoger&aacute; un total de<strong> 34 cursos intensivos<\/strong>, que se impartir&aacute;n de<strong> lunes a jueves<\/strong>, con una duraci&oacute;n total de <strong>50 horas<\/strong>. <strong>A1, A2, B1 y B2<\/strong> son los principales niveles sobre los que se dar&aacute; docencia, aunque var&iacute;a en funci&oacute;n de los idiomas que se ofertan: i<strong>ngl&eacute;s, alem&aacute;n, ruso, portugu&eacute;s, italiano, franc&eacute;s y polaco<\/strong>. Las sesiones se desarrollar&aacute;n tanto en horario <strong>de ma&ntilde;ana<\/strong> (de 9.00 a 13.30 horas), como en horario <strong>de tarde <\/strong>(de 15.00 a 19.30 horas).<a href='..\/..\/public\/docs\/548_ai_intensivos_de_verano.pdf'> <\/a><\/p>\n<p><a href='..\/..\/public\/docs\/548_ai_intensivos_de_verano.pdf'>(Consulta el cat&aacute;logo de cursos con fechas y horarios)<\/a><\/p>\n<p><a href='https:\/\/servicios.feu.ull.es\/Portal\/Idiomas\/Listado\/0\/0'>(Matric&uacute;late aqu&iacute;)<\/a><\/p>\n<p>La oferta se completa con <strong>cursos espec&iacute;ficos,<\/strong> como el de <strong>espa&ntilde;ol conversacional para extranjeros <\/strong>o de<strong> ingl&eacute;s jur&iacute;dico<\/strong>; as&iacute; como con otros preparatorios, principalmente, para los ex&aacute;menes de acreditaci&oacute;n de nivel<strong> B1 <\/strong>de lengua inglesa.<\/p>\n<p>Adem&aacute;s, las personas interesadas pueden participar en el proceso de adjudicaci&oacute;n de <a href='..\/..\/public\/docs\/535_x1_bases_becas_prolingua_2011_2012_cursos_de_verano.pdf'>25 becas <em>Prolingua<\/em><\/a>, financiado por la Direcci&oacute;n General de Universidades del Gobierno de Canarias, que cubren la mayor parte del importe econ&oacute;mico de los cursos. Estas becas est&aacute;n destinadas a estudiantado universitario y personas con titulaci&oacute;n que hayan finalizado sus estudios despu&eacute;s del 2006. La solicitud debe realizarse en la secretar&iacute;a de la Fundaci&oacute;n Empresa Universidad de La Laguna. <a href='..\/..\/public\/docs\/535_x1_bases_becas_prolingua_2011_2012_cursos_de_verano.pdf'>(Consulta las bases de las becas prolingua aqu&iacute;)<\/a>.<\/p>\n<p><strong>La sede de Adeje contar&aacute; con oferta de verano<\/strong><\/p>\n<p>La sede de Adeje del Servicio de Idiomas de la ULL tambi&eacute;n acoger&aacute;, durante este verano, cursos de ingl&eacute;s, alem&aacute;n y ruso, enfocados hacia la atenci&oacute;n al cliente, con una duraci&oacute;n de 30 horas, especialmente indicado para personas que trabajen en el sector tur&iacute;stico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se convocan 25 becas &#8216;Prolingua&#8217;, financiadas por el Gobierno de Canarias, que permitir\u00e1n costear gran parte del precio de los cursos. El plazo de solicitud para las becas se cierra el 8 de junio.<\/p>\n","protected":false},"author":36,"featured_media":10093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[173,672,780,1286],"featured_image_thumbnail_url":"https:\/\/fg.ull.es\/hemeroteca\/wp-content\/uploads\/sites\/14\/2015\/04\/757_w2_verano_en_el_servicio_de_idiomas-300x100.png","_links":{"self":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10094"}],"collection":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/comments?post=10094"}],"version-history":[{"count":0,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/posts\/10094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media\/10093"}],"wp:attachment":[{"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/media?parent=10094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/categories?post=10094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fg.ull.es\/hemeroteca\/wp-json\/wp\/v2\/tags?post=10094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}